{"id":92938,"date":"2022-03-06T21:25:44","date_gmt":"2022-03-06T21:25:44","guid":{"rendered":"http:\/\/192.168.64.2\/fr\/index.php\/2022\/03\/06\/colloque-sur-lexperience-mauritano-emiratie-dans-la-lutte-contre-la-pandemie-de-coronavirus\/"},"modified":"2022-07-05T11:14:49","modified_gmt":"2022-07-05T11:14:49","slug":"colloque-sur-lexperience-mauritano-emiratie-dans-la-lutte-contre-la-pandemie-de-coronavirus","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/92938","title":{"rendered":"Colloque sur l&#8217;exp\u00e9rience mauritano-\u00e9miratie dans la lutte contre la pand\u00e9mie de Coronavirus"},"content":{"rendered":"<p>Le Centre arabo-africain pour la communication et le d\u00e9veloppement et le Centre \u00e9mirati pour les recherches et les consultations ont organis\u00e9, dimanche soir \u00e0 Nouakchott un colloque m\u00e9diatique sous le th\u00e8me de &#8221; l&#8217;exp\u00e9rience mauritano-\u00e9miratie dans la lutte contre la pand\u00e9mie de Coronavirus&#8221;.<\/p>\n<p>Le colloque a \u00e9t\u00e9 anim\u00e9e par une conf\u00e9rence pr\u00e9sent\u00e9e par le directeur g\u00e9n\u00e9rale de la sant\u00e9 publique au minist\u00e8re de la Sant\u00e9, M. Mohamed Mahmoud Ould Ely Mahmoud et une autre pr\u00e9sent\u00e9e par la directrice des \u00e9tudes et des recherches dans le centre \u00e9mirati des \u00e9tudes et des consultations, Mme Aicha Khalfane Roumeithi sur l&#8217;exp\u00e9rience mauritano-\u00e9miratie dans la lutte contre le Coronavirus.<\/p>\n<p>Le directeur du Centre arabo-africain, M. Mohamed Salem Ould Dah a indiqu\u00e9, dans un mot prononc\u00e9 pour la circonstance, que pand\u00e9mie de la Covid-19 a pos\u00e9 de nombreux d\u00e9fis sanitaires et sociaux pour le monde entier, ce qui a exig\u00e9 de tous de conjuguer les efforts pour faire face \u00e0 ces d\u00e9fis.<\/p>\n<p>Il a ajout\u00e9 que l&#8217;int\u00e9r\u00eat du monde entier s&#8217;est focalis\u00e9 sur les moyens permettant de sauver les vies humaines, pr\u00e9cisant que la Mauritanie et les Emirats arabes unis ont d\u00e9ploy\u00e9 de grands efforts pour emp\u00eacher la propagation de la pand\u00e9mie, comptant sur leurs propres moyens.<\/p>\n<p>Il s&#8217;est en oputre f\u00e9licit\u00e9 du soutien accord\u00e9 par les Emirats arabes unis \u00e0 la Mauritanie.<\/p>\n<p>De son c\u00f4t\u00e9, le charg\u00e9 d&#8217;affaires de l&#8217;ambassade des Emirats arabes unis en Mauritanie, M. Hacen Echemili, a indiqu\u00e9 que les relations mauritano-\u00e9miraties ne sont pas le fruit de conditions difficiles donn\u00e9es mais plut\u00f4t sont des relations historiques, pr\u00e9cisant que le colloque d&#8217;aujourd&#8217;hui prouve cela.<\/p>\n<p>Il a enfin soulign\u00e9 que gr\u00e2ce \u00e0 la coordination entre les directions des deux pays, de nombreux projets importants ont \u00e9t\u00e9 ex\u00e9cut\u00e9s dans tous les domaines.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Centre arabo-africain pour la communication et le d\u00e9veloppement et le Centre \u00e9mirati pour les recherches et les consultations ont organis\u00e9, dimanche soir \u00e0 Nouakchott un colloque m\u00e9diatique sous le th\u00e8me de &#8221; l&#8217;exp\u00e9rience mauritano-\u00e9miratie dans la lutte contre la pand\u00e9mie de Coronavirus&#8221;<\/p>\n","protected":false},"author":1,"featured_media":195239,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[62476,63717],"class_list":["post-92938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-25","tag-nouakchott","tag-sbechire"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/92938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=92938"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/92938\/revisions"}],"predecessor-version":[{"id":195238,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/92938\/revisions\/195238"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/195239"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=92938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=92938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=92938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}