{"id":81441,"date":"2020-02-11T15:01:35","date_gmt":"2020-02-11T15:01:35","guid":{"rendered":"http:\/\/192.168.64.2\/fr\/index.php\/2020\/02\/11\/le-ministre-des-affaire-etrangeres-recoit-une-copie-figuree-des-lettres-de-creances-de-lambassadeur-du-tchad-en-mauritanie\/"},"modified":"2022-07-05T01:03:13","modified_gmt":"2022-07-05T01:03:13","slug":"le-ministre-des-affaire-etrangeres-recoit-une-copie-figuree-des-lettres-de-creances-de-lambassadeur-du-tchad-en-mauritanie","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/81441","title":{"rendered":"Le ministre des Affaire \u00e9trang\u00e8res re\u00e7oit une copie figur\u00e9e des lettres de cr\u00e9ances de l\u2019ambassadeur du Tchad en Mauritanie"},"content":{"rendered":"<p>Le ministre des Affaires \u00e9trang\u00e8res, de la coop\u00e9ration et des Mauritaniens de l\u2019Ext\u00e9rieur, M. Ismail Ould Cheikh Ahmed a re\u00e7u en audience mardi \u00e0 Nouakchott l\u2019ambassadeur du Tchad en Mauritanie r\u00e9sidant \u00e0 Niamey, SEM. Ousmane Souguikoko.<\/p>\n<p>Au cours de l\u2019entrevue, la diplomate tchadien a remis au ministre une copie figur\u00e9e de ses lettres de cr\u00e9ances.<\/p>\n<p>L\u2019audience s\u2019est d\u00e9roul\u00e9e en pr\u00e9sence de l\u2019ambassadeur Mohamed El Hanchi Ould Kettab, directeur du d\u00e9partement Afrique au minist\u00e8re des Affaires \u00e9trang\u00e8res, de la coop\u00e9ration et des Mauritaniens de l\u2019Ext\u00e9rieur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le ministre des Affaires \u00e9trang\u00e8res, de la coop\u00e9ration et des Mauritaniens de l\u2019Ext\u00e9rieur, M. Ismail Ould Cheikh Ahmed a re\u00e7u en audience mardi \u00e0 Nouakchott l\u2019ambassadeur du Tchad en Mauritanie r\u00e9sidant \u00e0 Niamey, SEM<\/p>\n","protected":false},"author":1,"featured_media":176290,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[63990,62969,62476],"class_list":["post-81441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-activites-gouvernementales","tag-alya","tag-nouakchott"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/81441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=81441"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/81441\/revisions"}],"predecessor-version":[{"id":176289,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/81441\/revisions\/176289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/176290"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=81441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=81441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=81441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}