{"id":70848,"date":"2018-09-19T15:01:05","date_gmt":"2018-09-19T15:01:05","guid":{"rendered":"http:\/\/192.168.64.2\/fr\/index.php\/2018\/09\/19\/rosso-les-autorites-administratives-intensifient-les-efforts-pour-drainer-les-eaux-de-pluie\/"},"modified":"2022-07-04T18:55:49","modified_gmt":"2022-07-04T18:55:49","slug":"rosso-les-autorites-administratives-intensifient-les-efforts-pour-drainer-les-eaux-de-pluie","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/70848","title":{"rendered":"Rosso: les autorit\u00e9s administratives intensifient les efforts pour drainer les eaux de pluie"},"content":{"rendered":"<p>le wali du Trarza, M. Moulaye Brahim Ould Moulaye Brahim, accompagn\u00e9 du Hakem de Rosso, a effectu\u00e9, mercredi matin, une visite dans les quartiers de la ville de Rosso affect\u00e9s par les eaux de pluie.<\/p>\n<p>Au cours de cette visite, le wali s&#8217;est rendu dans les chantiers du Centre National d\u2019Assainissement<br \/>\net la direction r\u00e9gionale de la protection civile  mis en oeuvre pour d\u00e9gager l\u2019eau des habitations et des rues au niveau de certains quartiers de la ville.<\/p>\n<p>Dans ce contexte, les autorit\u00e9s administratives ont distribu\u00e9 une vingtaine de pompes pour \u00e9vacuer les eaux stagnantes de l\u2019int\u00e9rieur des habitations.<\/p>\n<p>Les habitants de la ville de Rosso ont exprim\u00e9 leur satisfaction quant aux efforts d\u00e9ploy\u00e9s par les autorit\u00e9s publiques pour venir en aides aux sinistr\u00e9s.<\/p>\n<p>Auparavant, le wali a supervis\u00e9 le lancement des travaux visant \u00e0 att\u00e9nuer les effets des eaux de pluie au niveau des entr\u00e9es principales de la ville en r\u00e9parant les fissures et en approfondissant les canaux de drainage.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>le wali du Trarza, M. Moulaye Brahim Ould Moulaye Brahim, accompagn\u00e9 du Hakem de Rosso, a effectu\u00e9, mercredi matin, une visite dans les quartiers de la ville de Rosso affect\u00e9s par les eaux de pluie<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8672],"tags":[62947,62750,62477],"class_list":["post-70848","post","type-post","status-publish","format-standard","hentry","category-8672","tag-mariemz","tag-munina","tag-rosso"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/70848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=70848"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/70848\/revisions"}],"predecessor-version":[{"id":165692,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/70848\/revisions\/165692"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=70848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=70848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=70848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}