{"id":37615,"date":"2014-05-16T11:06:45","date_gmt":"2014-05-16T11:06:45","guid":{"rendered":"http:\/\/192.168.64.2\/fr\/index.php\/2014\/05\/16\/le-president-de-la-republique-felicite-le-roi-de-norvege-5\/"},"modified":"2022-07-04T05:23:18","modified_gmt":"2022-07-04T05:23:18","slug":"le-president-de-la-republique-felicite-le-roi-de-norvege-5","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/37615","title":{"rendered":"Le Pr\u00e9sident de la R\u00e9publique f\u00e9licite le Roi de Norv\u00e8ge"},"content":{"rendered":"<p>Le Pr\u00e9sident de la R\u00e9publique Monsieur Mohamed Ould Abdel Aziz a adress\u00e9 un message de f\u00e9licitation \u00e0 Sa Majest\u00e9 le Roi de Norv\u00e8ge \u00e0 l&#8217;occasion de la f\u00eate nationale de son pays.<\/p>\n<p>Ce message est ainsi libell\u00e9:<\/p>\n<p>&#8220;Majest\u00e9,<\/p>\n<p>A l&#8217;occasion de la f\u00eate nationale de la Norv\u00e8ge, il me plait de vous exprimer mes chaleureuses f\u00e9licitations ainsi que mes meilleurs voeux de sant\u00e9 et de bonheur pour Votre majest\u00e9, de progr\u00e8s et de prop\u00e9rit\u00e9 pour le peuple nov\u00e9gien ami.<\/p>\n<p>Tout comme je vous renouvelle notre souci de poursuivre les efforts pour renforcer et d\u00e9velopper les relations de coop\u00e9ration existant entre nos deux pays pour servir les int\u00e9r\u00eats des deux peuples amis.<\/p>\n<p>Veuillez agr\u00e9er Majest\u00e9, l&#8217;expressin de ma plus haute consid\u00e9ration.<\/p>\n<p>Mohamed Ould Abdel Aziz&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Pr\u00e9sident de la R\u00e9publique Monsieur Mohamed Ould Abdel Aziz a adress\u00e9 un message de f\u00e9licitation \u00e0 Sa Majest\u00e9 le Roi de Norv\u00e8ge \u00e0 l&#8217;occasion de la f\u00eate nationale de son pays.<\/p>\n<p>Ce message est ainsi<\/p>\n","protected":false},"author":1,"featured_media":132448,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[63991,63109,62969,62476],"class_list":["post-37615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-activites-presidentielles","tag-ahmedabd","tag-alya","tag-nouakchott"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/37615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=37615"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/37615\/revisions"}],"predecessor-version":[{"id":132447,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/37615\/revisions\/132447"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/132448"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=37615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=37615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=37615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}