{"id":297003,"date":"2026-06-16T18:32:33","date_gmt":"2026-06-16T18:32:33","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=297003"},"modified":"2026-06-16T18:32:33","modified_gmt":"2026-06-16T18:32:33","slug":"lancement-du-colloque-arabe-sur-la-numerisation-de-ladministration-publique","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/297003","title":{"rendered":"Lancement du colloque arabe sur la num\u00e9risation de l&#8217;administration publique"},"content":{"rendered":"<p>Le colloque arabe sur \u00ab La num\u00e9risation de l&#8217;administration publique et l&#8217;avenir des services publics \u00bb a \u00e9t\u00e9 lanc\u00e9 mardi \u00e0 Nouakchott, organis\u00e9 par l&#8217;\u00c9cole Nationale d&#8217;Administration, de Journalisme et de Magistrature en coop\u00e9ration avec le minist\u00e8re de la Transformation num\u00e9rique et de la modernisation de l&#8217;administration, l&#8217;Organisation arabe pour l&#8217;Education, la Culture et la Science (ALECSO) et l&#8217;Organisation arabe pour le d\u00e9veloppement administratif.<\/p>\n<p>Le colloque vise \u00e0 renforcer l&#8217;\u00e9change d&#8217;expertise et d&#8217;exp\u00e9riences arabes dans le domaine de la transformation num\u00e9rique et de la modernisation de l&#8217;administration publique, et \u00e0 examiner les meilleures pratiques li\u00e9es \u00e0 la num\u00e9risation des services gouvernementaux, en plus d&#8217;examiner les perspectives d&#8217;utilisation des technologies modernes et de l&#8217;intelligence artificielle pour am\u00e9liorer la qualit\u00e9 des services publics et accro\u00eetre l&#8217;efficacit\u00e9 des performances administratives.<\/p>\n<p>Dans un discours prononc\u00e9 \u00e0 cette occasion, le ministre de la Transformation num\u00e9rique et de la Modernisation de l&#8217;Administration, M. Ahmed Salem Ould Bede, a soulign\u00e9 que la num\u00e9risation de l&#8217;administration publique n&#8217;est plus seulement une option technique, mais est devenue un projet de r\u00e9forme int\u00e9gr\u00e9e visant \u00e0 d\u00e9velopper la performance des \u00e9quipements publics et \u00e0 am\u00e9liorer la qualit\u00e9 des services rendus aux citoyens, en simplifiant les proc\u00e9dures administratives, en renfor\u00e7ant la transparence et en s&#8217;appuyant sur les donn\u00e9es et les connaissances dans la prise de d\u00e9cision.<\/p>\n<p>Il a ajout\u00e9 que la Mauritanie a fait de la transformation num\u00e9rique une option strat\u00e9gique dans la mise en \u0153uvre des directives de Son Excellence le Pr\u00e9sident de la R\u00e9publique, M. Mohamed Ould Cheikh Al-Ghazouani, et une concr\u00e9tisation du programme du gouvernement, soulignant que cette tendance a permis le lancement de nombreux projets, plateformes et services num\u00e9riques visant \u00e0 rapprocher le service public des citoyens et \u00e0 accro\u00eetre l&#8217;efficacit\u00e9 de la performance administrative.<\/p>\n<p>Il a soulign\u00e9 que l\u2019investissement dans l\u2019\u00e9l\u00e9ment humain reste le fondement du succ\u00e8s du processus de num\u00e9risation et de la construction d\u2019une administration moderne qui r\u00e9pond aux exigences de d\u00e9veloppement et aux aspirations des citoyens.<\/p>\n<p>\u00c0 son tour, le directeur g\u00e9n\u00e9ral de l&#8217;\u00c9cole nationale d&#8217;administration, de journalisme et de magistrature, M. Mohamed Yahya Ould Said, a indiqu\u00e9 que ce colloque constitue un espace d&#8217;\u00e9change d&#8217;expertises et d&#8217;exp\u00e9riences, passant en revue les derni\u00e8res tendances dans le domaine de l&#8217;administration \u00e9lectronique et de la transformation num\u00e9rique, et anticipant l&#8217;avenir du service public \u00e0 la lumi\u00e8re des d\u00e9veloppements rapides de la technologie et de l&#8217;intelligence artificielle.<\/p>\n<p>Il a soulign\u00e9 le r\u00f4le central jou\u00e9 par le Minist\u00e8re de la Transformation Num\u00e9rique et de la Modernisation de l&#8217;Administration pour suivre cette voie en d\u00e9veloppant les services \u00e9lectroniques et en soutenant la num\u00e9risation des secteurs gouvernementaux, notant que la plateforme de plaintes et de notifications \u00ab Ain \u00bb a contribu\u00e9 \u00e0 renforcer l&#8217;interaction directe entre le citoyen et l&#8217;administration et \u00e0 consolider les principes de transparence et de bonne gouvernance.<\/p>\n<p>Il a \u00e9galement soulign\u00e9 la volont\u00e9 de l&#8217;\u00e9cole d&#8217;accompagner cette transformation en num\u00e9risant sa gestion administrative et p\u00e9dagogique et en d\u00e9veloppant des programmes de formation continue dans les domaines de la technologie moderne, renfor\u00e7ant ainsi son r\u00f4le d&#8217;institution nationale de formation et d&#8217;\u00e9change d&#8217;exp\u00e9riences.<\/p>\n<p>De son c\u00f4t\u00e9, le directeur du D\u00e9partement des sciences et de la recherche scientifique de l&#8217;Organisation arabe pour l&#8217;\u00e9ducation, la culture et la science (ALECSO), M. Mohamed Sanad Abun, a soulign\u00e9 que le succ\u00e8s de la transformation num\u00e9rique n&#8217;est pas seulement li\u00e9 \u00e0 la possession de la technologie, mais aussi \u00e0 la capacit\u00e9 des institutions \u00e0 l&#8217;employer \u00e0 travers des comp\u00e9tences humaines qualifi\u00e9es et des visions strat\u00e9giques claires.<\/p>\n<p>Il a soulign\u00e9 que ce colloque constitue une plate-forme importante pour \u00e9changer des exp\u00e9riences et renforcer la coop\u00e9ration arabe dans le domaine de la modernisation de l&#8217;administration gouvernementale, ce qui contribue au d\u00e9veloppement des services publics et \u00e0 suivre le rythme des transformations rapides que conna\u00eet le monde.<\/p>\n<p>Dans le m\u00eame contexte, le pr\u00e9sident du Groupe de gestion strat\u00e9gique et de qualit\u00e9 \u00e0 l&#8217;Organisation arabe de d\u00e9veloppement administratif, M. Hassan Diab, a soulign\u00e9 que la transformation num\u00e9rique est devenue une voie strat\u00e9gique qui remod\u00e8le les m\u00e9thodes de gestion et de fourniture des services publics \u00e0 la lumi\u00e8re des d\u00e9veloppements rapides dans les domaines de l&#8217;intelligence artificielle et des donn\u00e9es.<\/p>\n<p>Il a ajout\u00e9 que la construction d&#8217;une administration gouvernementale moderne n\u00e9cessite de renforcer la capacit\u00e9 des institutions \u00e0 apprendre, s&#8217;adapter, innover et g\u00e9rer le changement, en garantissant une efficacit\u00e9 accrue des performances et en am\u00e9liorant la qualit\u00e9 des services fournis aux citoyens.<\/p>\n<p>Le programme du colloque comprend des sessions scientifiques et des ateliers sp\u00e9cialis\u00e9s qui abordent les exp\u00e9riences arabes pionni\u00e8res en mati\u00e8re de transformation num\u00e9rique, de simplification des proc\u00e9dures administratives, de cyber s\u00e9curit\u00e9, de souverainet\u00e9 num\u00e9rique, de gouvernement intelligent et des implications de la num\u00e9risation sur la performance des installations publiques et la qualit\u00e9 des services fournis aux citoyens.<\/p>\n<p>Le colloque a \u00e9t\u00e9 ouvert en pr\u00e9sence de la ministre de la Fonction publique et du Travail, Mme Mariem Bo\u00efdiel Houmeid, du conseiller du Premier ministre, M. Haroun Ammar Id\u00e8kbi, et d&#8217;un certain nombre de responsables, d&#8217;experts et de personnes int\u00e9ress\u00e9es par les questions de transformation num\u00e9rique et d&#8217;administration publique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le colloque arabe sur \u00ab La num\u00e9risation de l&#8217;administration publique et l&#8217;avenir des services publics \u00bb a \u00e9t\u00e9 lanc\u00e9 mardi \u00e0 Nouakchott, organis\u00e9 par l&#8217;\u00c9cole Nationale d&#8217;Administration, de Journalisme et de Magistrature en coop\u00e9ration avec le minist\u00e8re de la Transformation num\u00e9rique et de la modernisation de l&#8217;administration, l&#8217;Organisation arabe pour l&#8217;Education, la Culture et la [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":297004,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63920,63957,63959],"tags":[],"class_list":["post-297003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-fil-dactualite","category-mauritanie"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/297003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=297003"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/297003\/revisions"}],"predecessor-version":[{"id":297005,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/297003\/revisions\/297005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/297004"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=297003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=297003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=297003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}