{"id":295357,"date":"2026-05-16T13:03:46","date_gmt":"2026-05-16T13:03:46","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=295357"},"modified":"2026-05-16T13:05:48","modified_gmt":"2026-05-16T13:05:48","slug":"secteur-de-la-sante-un-engagement-fort-pour-la-construction-dun-systeme-de-sante-complet-de-haute-qualite-et-centre-sur-le-citoyen","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/295357","title":{"rendered":"Secteur de la sant\u00e9 : Un engagement fort pour la construction d\u2019un syst\u00e8me de sant\u00e9 complet, de haute qualit\u00e9 et centr\u00e9 sur le citoyen"},"content":{"rendered":"<p>Le syst\u00e8me de sant\u00e9 mauritanien a connu des transformations radicales ces derni\u00e8res ann\u00e9es, s\u2019orientant vers une r\u00e9forme globale. Cette \u00e9volution refl\u00e8te la vision de Son Excellence le Pr\u00e9sident de la R\u00e9publique, M. Mohamed Ould Cheikh El Ghazouani, qui vise \u00e0 faire du syst\u00e8me de sant\u00e9 une priorit\u00e9 afin qu\u2019il atteigne la place qui lui revient en termes de qualit\u00e9 et d\u2019accessibilit\u00e9 pour tous les citoyens.<\/p>\n<p>Dans ce contexte, le conseiller charg\u00e9 de la communication du minist\u00e8re de la Sant\u00e9, M. Ahmed Badah, a expliqu\u00e9 dans une interview accord\u00e9e \u00e0 l\u2019Agence mauritanienne d\u2019information (AMI) que, conform\u00e9ment aux engagements du Pr\u00e9sident en faveur d\u2019un syst\u00e8me de sant\u00e9 plus \u00e9quitable et plus accessible, et dans le cadre de la politique gouvernementale d\u2019\u00e9largissement de l\u2019acc\u00e8s aux services de sant\u00e9 et d\u2019am\u00e9lioration de leur qualit\u00e9, les investissements publics dans le secteur de la sant\u00e9 se poursuivent \u00e0 travers des programmes int\u00e9gr\u00e9s.<\/p>\n<p>Ces programmes visent \u00e0 rapprocher les services de base des populations, \u00e0 \u00e9tendre la couverture sanitaire aux wilayas de l\u2019int\u00e9rieur du pays et \u00e0 renforcer l&#8217;offre d&#8217;h\u00f4pitaux sp\u00e9cialis\u00e9s et de r\u00e9f\u00e9rence.<\/p>\n<p>Il a expliqu\u00e9 qu&#8217;apr\u00e8s le Programme d&#8217;urgence de d\u00e9veloppement de la ville de Nouakchott n\u00b0 1, ax\u00e9 sur le rapprochement des services de sant\u00e9 de base des citoyens de la capitale gr\u00e2ce \u00e0 la construction, la r\u00e9novation et l&#8217;\u00e9quipement de 28 centres de sant\u00e9 dans diff\u00e9rentes moughataas de Nouakchott, le programme d&#8217;acc\u00e8s aux services de base dans les wilayas int\u00e9rieures a \u00e9t\u00e9 lanc\u00e9 afin de renforcer cette approche \u00e0 l&#8217;\u00e9chelle nationale. Cette extension de la couverture sanitaire dans les wilayas int\u00e9rieures comprend la construction de deux h\u00f4pitaux r\u00e9gionaux, de trois h\u00f4pitaux de moughataas, de 17 centres de sant\u00e9 et de 204 nouveaux postes de sant\u00e9, ainsi que la r\u00e9habilitation de 84 \u00e9tablissements de sant\u00e9 existants et l&#8217;acquisition de 92 ambulances. Ces initiatives contribueront \u00e0 am\u00e9liorer l&#8217;acc\u00e8s aux services de sant\u00e9 et \u00e0 les rapprocher des populations des wilaya de l\u2019int\u00e9rieur.<\/p>\n<p>Poursuivant l&#8217;investissement public dans le syst\u00e8me national de sant\u00e9, il a indiqu\u00e9 que la deuxi\u00e8me phase du Programme de d\u00e9veloppement de la ville de Nouakchott vise \u00e0 renforcer l&#8217;offre d&#8217;h\u00f4pitaux sp\u00e9cialis\u00e9s et de r\u00e9f\u00e9rence, notamment dans les domaines les plus sollicit\u00e9s, tels que les urgences, les soins intensifs, la maternit\u00e9, les grands br\u00fbl\u00e9s, le traitement des addictions et la dialyse.<\/p>\n<p>Il a pr\u00e9cis\u00e9 que le volet sant\u00e9 du Programme de d\u00e9veloppement Nouakchott 2 consiste \u00e0 construire et \u00e0 \u00e9quiper les services d&#8217;urgences selon les normes modernes, afin d&#8217;am\u00e9liorer la capacit\u00e9 de prise en charge rapide des cas critiques. Ce volet sera initialement mis en \u0153uvre au Centre hospitalier national, au Centre hospitalier de l&#8217;Amiti\u00e9, au Centre hospitalier Cheikh Zayed, au Centre hospitalier M\u00e8re-Enfant et au Centre national de cardiologie.<\/p>\n<p>Il a ajout\u00e9 que ce volet comprend \u00e9galement :<\/p>\n<p>&#8211; L&#8217;agrandissement et l&#8217;\u00e9quipement des unit\u00e9s de soins intensifs, permettant ainsi d&#8217;accro\u00eetre la capacit\u00e9 hospitali\u00e8re et d&#8217;am\u00e9liorer la qualit\u00e9 des soins pour les cas critiques et les patients n\u00e9cessitant des soins intensifs.<\/p>\n<p>&#8211; Construction et \u00e9quipement d&#8217;un grand centre de maternit\u00e9 et de n\u00e9onatalogie, incluant la cr\u00e9ation de la premi\u00e8re unit\u00e9 de maternit\u00e9 de niveau 3, ce qui permettra d&#8217;am\u00e9liorer la prise en charge des cas complexes de sant\u00e9 maternelle et infantile et de renforcer les services destin\u00e9s aux nouveau-n\u00e9s et aux pr\u00e9matur\u00e9s.<\/p>\n<p>&#8211; Construction et \u00e9quipement de la premi\u00e8re unit\u00e9 de traitement des grands br\u00fbl\u00e9s, afin d&#8217;offrir des services nationaux sp\u00e9cialis\u00e9s dans ce domaine et de r\u00e9duire le recours aux transferts externes.<\/p>\n<p>&#8211; Construction et \u00e9quipement de la premi\u00e8re unit\u00e9 de traitement des addictions, dans le cadre d&#8217;une approche m\u00e9dico-sociale de la prise en charge des troubles mentaux et des addictions.<\/p>\n<p>&#8211; Construction de trois nouveaux centres de dialyse, d&#8217;une capacit\u00e9 suppl\u00e9mentaire de 100 lits, ce qui permettra de d\u00e9sengorger les centres existants et d&#8217;am\u00e9liorer l&#8217;acc\u00e8s aux soins pour les patients souffrant d&#8217;insuffisance r\u00e9nale.<\/p>\n<p>Le conseiller a conclu que ces trois programmes de sant\u00e9 constituent une mise en \u0153uvre concr\u00e8te de la vision de Son Excellence le Pr\u00e9sident de la R\u00e9publique visant \u00e0 b\u00e2tir un syst\u00e8me de sant\u00e9 \u00e9quitable, accessible \u00e0 tous et capable de r\u00e9pondre aux besoins fondamentaux et sp\u00e9cifiques de chaque citoyen, \u00e0 travers un travail int\u00e9gr\u00e9 et de grande qualit\u00e9, qui a d\u00e9but\u00e9 par le rapprochement des services de base de la capitale, puis l&#8217;\u00e9largissement de l&#8217;acc\u00e8s aux soins de sant\u00e9 dans les wilayas int\u00e9rieures, et enfin le renforcement de l&#8217;offre d&#8217;h\u00f4pitaux sp\u00e9cialis\u00e9s et de r\u00e9f\u00e9rence. Ceci garantira un acc\u00e8s \u00e9quitable \u00e0 des services de sant\u00e9 de qualit\u00e9 et renforcera la confiance des citoyens dans le syst\u00e8me de sant\u00e9 publique \u00e0 travers le pays.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le syst\u00e8me de sant\u00e9 mauritanien a connu des transformations radicales ces derni\u00e8res ann\u00e9es, s\u2019orientant vers une r\u00e9forme globale. Cette \u00e9volution refl\u00e8te la vision de Son Excellence le Pr\u00e9sident de la R\u00e9publique, M. Mohamed Ould Cheikh El Ghazouani, qui vise \u00e0 faire du syst\u00e8me de sant\u00e9 une priorit\u00e9 afin qu\u2019il atteigne la place qui lui revient [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":295358,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63918,63957,63959],"tags":[],"class_list":["post-295357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autres","category-fil-dactualite","category-mauritanie"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/295357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=295357"}],"version-history":[{"count":2,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/295357\/revisions"}],"predecessor-version":[{"id":295360,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/295357\/revisions\/295360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/295358"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=295357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=295357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=295357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}