{"id":294092,"date":"2026-04-27T19:56:15","date_gmt":"2026-04-27T19:56:15","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=294092"},"modified":"2026-04-27T19:56:15","modified_gmt":"2026-04-27T19:56:15","slug":"kiffa-lancement-dun-atelier-regional-de-formation-sur-les-actions-preventives-face-aux-defis-climatiques","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/294092","title":{"rendered":"Kiffa : lancement d\u2019un atelier r\u00e9gional de formation sur les actions pr\u00e9ventives face aux d\u00e9fis climatiques"},"content":{"rendered":"<div class=\"row\"><\/div>\n<div class=\"row\">\n<div class=\"cell auto-size\">\n<div class=\"set-border bd-gray padding10 margin10 no-margin-right no-margin-left \" dir=\"ltr\">\n<p>Les travaux d\u2019un atelier r\u00e9gional de formation destin\u00e9 aux acteurs nationaux et locaux sur l\u2019am\u00e9lioration de la compr\u00e9hension et de la mise en \u0153uvre des actions anticipatives, de l\u2019alerte pr\u00e9coce et des interventions face aux d\u00e9fis climatiques ont d\u00e9but\u00e9, ce lundi \u00e0 Kiffa. Cette rencontre est organis\u00e9e par le Programme alimentaire mondial.<\/p>\n<p>Dans une allocution prononc\u00e9e \u00e0 cette occasion, le conseiller du wali de l\u2019Assaba charg\u00e9 des affaires politiques et sociales, M. Cheikh Mohamed Abdallahi Khawah, a indiqu\u00e9 que cet atelier vise \u00e0 former les b\u00e9n\u00e9ficiaires sur la mise en \u0153uvre des actions anticipatives pour faire face aux d\u00e9fis climatiques, \u00e9conomiques, s\u00e9curitaires et sanitaires auxquels la wilaya est confront\u00e9e, en vue de prendre les mesures n\u00e9cessaires pour prot\u00e9ger les populations et leurs biens.<\/p>\n<p>Il a ajout\u00e9 que les objectifs de cette rencontre s\u2019inscrivent dans le cadre du programme de Son Excellence le Pr\u00e9sident de la R\u00e9publique, M. Mohamed Ould Cheikh El Ghazouani, visant \u00e0 am\u00e9liorer les conditions des couches vuln\u00e9rables, \u00e0 renforcer leur protection et \u00e0 soutenir leur r\u00e9silience face aux crises et aux al\u00e9as climatiques.<\/p>\n<p>Pour sa part, le maire adjoint de la commune de Kiffa, M. Yesslem Ould Beyane, a soulign\u00e9 que cet atelier contribue \u00e0 renforcer les capacit\u00e9s des acteurs locaux en mati\u00e8re d\u2019alerte pr\u00e9coce et \u00e0 mieux orienter leurs interventions en fonction des besoins sp\u00e9cifiques de chaque situation.<\/p>\n<p>De son c\u00f4t\u00e9, le repr\u00e9sentant du Programme alimentaire mondial \u00e0 Kiffa a affirm\u00e9 que cette session de formation r\u00e9gionale vise \u00e0 sensibiliser et \u00e0 renforcer les capacit\u00e9s des parties prenantes, tant nationales que locales, en mati\u00e8re d\u2019actions anticipatives dans la wilaya de l\u2019Assaba.<\/p>\n<p>Il a pr\u00e9cis\u00e9 que cet atelier a pour objectif de d\u00e9velopper les comp\u00e9tences des services techniques et des acteurs locaux, tout en expliquant les m\u00e9canismes de s\u00e9lection et de priorisation des activit\u00e9s \u00e0 mettre en \u0153uvre, ainsi que l\u2019\u00e9valuation des d\u00e9fis li\u00e9s au d\u00e9veloppement, \u00e0 l\u2019ex\u00e9cution et \u00e0 l\u2019institutionnalisation des actions anticipatives.<\/p>\n<p>L\u2019atelier s\u2019est d\u00e9roul\u00e9 en pr\u00e9sence du hakem de la moughataa de Kiffa, M. Ali Ahmedou El Houssein, de la vice-pr\u00e9sidente du Conseil r\u00e9gional de l\u2019Assaba, Mme Tahya Brahim Bousseif, ainsi que de plusieurs chefs de services r\u00e9gionaux.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Les travaux d\u2019un atelier r\u00e9gional de formation destin\u00e9 aux acteurs nationaux et locaux sur l\u2019am\u00e9lioration de la compr\u00e9hension et de la mise en \u0153uvre des actions anticipatives, de l\u2019alerte pr\u00e9coce et des interventions face aux d\u00e9fis climatiques ont d\u00e9but\u00e9, ce lundi \u00e0 Kiffa. Cette rencontre est organis\u00e9e par le Programme alimentaire mondial. Dans une allocution [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":294093,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63918,63957],"tags":[],"class_list":["post-294092","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autres","category-fil-dactualite"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/294092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=294092"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/294092\/revisions"}],"predecessor-version":[{"id":294094,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/294092\/revisions\/294094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/294093"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=294092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=294092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=294092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}