{"id":291823,"date":"2026-03-24T20:43:51","date_gmt":"2026-03-24T20:43:51","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=291823"},"modified":"2026-03-24T20:43:51","modified_gmt":"2026-03-24T20:43:51","slug":"le-wali-de-ladrar-appelle-a-la-lutte-contre-la-drogue-et-souligne-lamelioration-du-reseau-deau-a-atar","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/291823","title":{"rendered":"Le wali de l\u2019Adrar appelle \u00e0 la lutte contre la drogue et souligne l\u2019am\u00e9lioration du r\u00e9seau d\u2019eau \u00e0 Atar"},"content":{"rendered":"<div class=\"row\">\n<div class=\"cell auto-size bd-gray\" dir=\"ltr\"><\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"cell auto-size\">\n<div class=\"set-border bd-gray padding10 margin10 no-margin-right no-margin-left \" dir=\"ltr\">\n<p>Le wali de l\u2019Adrar, M. Abdallahi Ould Mohamed Mahmoud, a appel\u00e9, lors d\u2019une r\u00e9union tenue dans les locaux de la wilaya \u00e0 Atar, \u00e0 la mobilisation de toutes les composantes de la soci\u00e9t\u00e9 pour lutter contre le ph\u00e9nom\u00e8ne de la drogue, mettant en garde contre sa dangerosit\u00e9 et ses r\u00e9percussions n\u00e9gatives, notamment sur les jeunes.<\/p>\n<p>Le wali a soulign\u00e9 que ce ph\u00e9nom\u00e8ne est \u00e9tranger \u00e0 la soci\u00e9t\u00e9, insistant sur la n\u00e9cessit\u00e9 de le combattre \u00e0 travers une approche globale incluant l\u2019organisation de campagnes de sensibilisation dans toutes les moughataas, l\u2019introduction de contenus \u00e9ducatifs dans les \u00e9tablissements scolaires, ainsi que l\u2019unification des pr\u00eaches du vendredi afin de mieux faire conna\u00eetre ses dangers.<\/p>\n<p>Dans un autre registre, le wali a pr\u00e9sid\u00e9 une seconde r\u00e9union consacr\u00e9e \u00e0 l\u2019\u00e9valuation de la situation du r\u00e9seau d\u2019eau dans la ville, en application des orientations du Pr\u00e9sident de la R\u00e9publique, Son Excellence M. Mohamed Ould Cheikh El Ghazouani, notamment \u00e0 l\u2019approche de la saison estivale.<\/p>\n<p>Les responsables pr\u00e9sents ont indiqu\u00e9 que la wilaya a connu d\u2019importantes extensions du r\u00e9seau d\u2019eau au cours des derni\u00e8res ann\u00e9es, tout en poursuivant actuellement les efforts visant \u00e0 am\u00e9liorer et \u00e9tendre les services afin de couvrir l\u2019ensemble des quartiers, en r\u00e9ponse aux besoins des populations.<\/p>\n<p>Les deux r\u00e9unions se sont d\u00e9roul\u00e9es en pr\u00e9sence des autorit\u00e9s administratives et s\u00e9curitaires ainsi que des chefs des services r\u00e9gionaux.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le wali de l\u2019Adrar, M. Abdallahi Ould Mohamed Mahmoud, a appel\u00e9, lors d\u2019une r\u00e9union tenue dans les locaux de la wilaya \u00e0 Atar, \u00e0 la mobilisation de toutes les composantes de la soci\u00e9t\u00e9 pour lutter contre le ph\u00e9nom\u00e8ne de la drogue, mettant en garde contre sa dangerosit\u00e9 et ses r\u00e9percussions n\u00e9gatives, notamment sur les jeunes. [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":291824,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63918,63957],"tags":[],"class_list":["post-291823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autres","category-fil-dactualite"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/291823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=291823"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/291823\/revisions"}],"predecessor-version":[{"id":291825,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/291823\/revisions\/291825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/291824"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=291823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=291823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=291823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}