{"id":287975,"date":"2026-01-27T14:19:49","date_gmt":"2026-01-27T14:19:49","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=287975"},"modified":"2026-01-27T14:19:49","modified_gmt":"2026-01-27T14:19:49","slug":"ouverture-dun-atelier-consultatif-dedie-a-la-municipalite-de-sebkha-sur-le-projet-de-protection-et-de-valorisation-de-la-plage-de-nouakchott","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/287975","title":{"rendered":"Ouverture d&#8217;un atelier consultatif d\u00e9di\u00e9 \u00e0 la municipalit\u00e9 de Sebkha sur le projet de protection et de valorisation de la plage de Nouakchott"},"content":{"rendered":"<p>Le minist\u00e8re de l\u2019Habitat, de l&#8217;Urbanisme et de l&#8217;Am\u00e9nagement du Territoire a organis\u00e9, mardi \u00e0 Nouakchott, un atelier de consultation d\u00e9di\u00e9 \u00e0 la municipalit\u00e9 de Sabkha sur le projet de protection et de valorisation du littoral de Nouakchott, en collaboration avec la soci\u00e9t\u00e9 de r\u00e9habilitation du littoral de Nouakchott et le Fonds d&#8217;investissement fran\u00e7ais.<\/p>\n<p>Cet atelier s&#8217;inscrit dans une s\u00e9rie d&#8217;autres organis\u00e9s dans les municipalit\u00e9s de Tevragh Zeina, Sebkha et El Mina dans le but de prot\u00e9ger la ville contre les risques naturels, de renforcer son attractivit\u00e9 et de transformer le littoral, zone \u00e0 risque, en un espace s\u00fbr et ouvert \u00e0 tous, contribuant ainsi \u00e0 l&#8217;am\u00e9lioration de la qualit\u00e9 de vie.<\/p>\n<p>Le charg\u00e9 de mission au minist\u00e8re de l\u2019Habitat, de l&#8217;Urbanisme et de l&#8217;Am\u00e9nagement du Territoire, M. Ahmed Mohamed Baba, a indiqu\u00e9 que cette rencontre s&#8217;inscrit dans le cadre de la mise en \u0153uvre des directives de Son Excellence le Pr\u00e9sident de la R\u00e9publique, Monsieur Mohamed Ould Cheikh El Ghazouani, visant \u00e0 am\u00e9liorer le cadre de vie des citoyens, \u00e0 pr\u00e9server leurs moyens de subsistance et \u00e0 d\u00e9velopper et moderniser les villes mauritaniennes.<\/p>\n<p>Il a ajout\u00e9 que la mise en \u0153uvre de ces directives refl\u00e8te la volont\u00e9 de Mme Naha Hamdi Mouknass, ministre du l\u2019Habitat, de l&#8217;Urbanisme et de l&#8217;Am\u00e9nagement du Territoire, de concentrer les efforts du secteur sur le d\u00e9veloppement et la modernisation de la capitale Nouakchott, soulignant l&#8217;importance exceptionnelle qu&#8217;elle accorde au projet de protection et de d\u00e9veloppement du littoral de la ville, ainsi que son suivi continu de la pr\u00e9paration et de la mise en \u0153uvre de ses plans, dans le but de le transformer d&#8217;une zone menac\u00e9e en un espace moderne, s\u00fbr, attrayant et accessible \u00e0 tous, contribuant \u00e0 am\u00e9liorer la qualit\u00e9 de vie et \u00e0 renforcer le d\u00e9veloppement \u00e9conomique et touristique.<\/p>\n<p>Il a assur\u00e9 que toutes les observations et opinions seraient consign\u00e9es et examin\u00e9es avec la plus grande attention, et qu&#8217;un rapport d\u00e9taill\u00e9 sera pr\u00e9sent\u00e9 \u00e0 la ministre.<\/p>\n<p>Le charg\u00e9 de mission a pr\u00e9cis\u00e9 que, dans le cadre de la politique du secteur visant \u00e0 renforcer la consultation publique, \u00e0 ancrer les principes de transparence et \u00e0 associer tous les acteurs \u00e0 la cr\u00e9ation et au d\u00e9veloppement de l&#8217;espace urbain, une enqu\u00eate publique d&#8217;un mois a \u00e9t\u00e9 ouverte sur les plans des zones faisant l&#8217;objet de la consultation dans les communes de Tevragh-Zeina, Sebkha et El Mina.<\/p>\n<p>Il a ajout\u00e9 que le secteur a ouvert des registres au si\u00e8ge de la municipalit\u00e9 et du minist\u00e8re pour consigner les observations, ainsi qu&#8217;une plateforme \u00e9lectronique sur le site web du minist\u00e8re pour recueillir les avis et suggestions des citoyens.<\/p>\n<p>Pour sa part, le maire adjoint de la municipalit\u00e9 de Sebkha, M. Abou Djibi Diallo, a soulign\u00e9 que cet atelier constitue une \u00e9tape fondamentale dans le processus de planification du littoral faisant observer que la participation active des citoyens, des autorit\u00e9s locales et de toutes les parties concern\u00e9es permet de recueillir les opinions, les pr\u00e9occupations, les suggestions et les aspirations des populations directement concern\u00e9es, ce qui contribue \u00e0 enrichir les projets et \u00e0 anticiper leurs impacts sociaux, \u00e9conomiques et environnementaux.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le minist\u00e8re de l\u2019Habitat, de l&#8217;Urbanisme et de l&#8217;Am\u00e9nagement du Territoire a organis\u00e9, mardi \u00e0 Nouakchott, un atelier de consultation d\u00e9di\u00e9 \u00e0 la municipalit\u00e9 de Sabkha sur le projet de protection et de valorisation du littoral de Nouakchott, en collaboration avec la soci\u00e9t\u00e9 de r\u00e9habilitation du littoral de Nouakchott et le Fonds d&#8217;investissement fran\u00e7ais. Cet [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":287976,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63918,63957,63959],"tags":[],"class_list":["post-287975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autres","category-fil-dactualite","category-mauritanie"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/287975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=287975"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/287975\/revisions"}],"predecessor-version":[{"id":287977,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/287975\/revisions\/287977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/287976"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=287975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=287975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=287975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}