{"id":287446,"date":"2026-01-17T19:37:40","date_gmt":"2026-01-17T19:37:40","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=287446"},"modified":"2026-01-17T20:53:58","modified_gmt":"2026-01-17T20:53:58","slug":"le-president-de-la-republique-regagne-nouakchott-apres-avoir-participe-a-la-ceremonie-dinvestiture-du-president-de-la-republique-de-guinee","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/287446","title":{"rendered":"Le Pr\u00e9sident de la R\u00e9publique regagne Nouakchott apr\u00e8s avoir particip\u00e9 \u00e0 la c\u00e9r\u00e9monie d&#8217;investiture du Pr\u00e9sident de la R\u00e9publique de Guin\u00e9e"},"content":{"rendered":"<p>Son Excellence le Pr\u00e9sident de la R\u00e9publique, Monsieur Mohamed Ould Cheikh El Ghazouani, a regagn\u00e9 ce samedi soir Nouakchott, en provenance de Conakry, apr\u00e8s avoir particip\u00e9 \u00e0 la c\u00e9r\u00e9monie d&#8217;investiture de Son Excellence Monsieur Mamady Doumbouya, Pr\u00e9sident de la R\u00e9publique de Guin\u00e9e.<\/p>\n<p>Son Excellence le Pr\u00e9sident de la R\u00e9publique a \u00e9t\u00e9 accueilli \u00e0 l&#8217;a\u00e9roport international de Nouakchott Oumtounsy par le Premier Ministre, Monsieur El Moctar Ould Djay, les ministres conseillers \u00e0 la Pr\u00e9sidence de la R\u00e9publique, Monsieur Mohamed Mahmoud Ould Cheikh Abdallahi Ben Baya et Madame A\u00efssata Ba Yahya, le ministre de la Justice, Monsieur Mohamed Ould Soueidatt, le ministre de la D\u00e9fense, des Affaires des Retrait\u00e9s et des fils des Martyrs, Monsieur Hanena Ould Sidi, le ministre de l&#8217;Int\u00e9rieur, de la promotion de la D\u00e9centralisation et du D\u00e9veloppement Local, Monsieur Mohamed Ahmed Ould Mohamed Lemine, le Chef d&#8217;\u00c9tat-Major particulier du Pr\u00e9sident de la R\u00e9publique, le G\u00e9n\u00e9ral Mohamed Mokhtar Cheikh Meni, la Directrice Adjointe du Cabinet du Pr\u00e9sident de la R\u00e9publique, Madame Gandega Fatimata, le wali de Nouakchott Ouest, Monsieur Hammoud Ould M&#8217;hamed, et la Pr\u00e9sidente de la R\u00e9gion de Nouakchott, Madame Fatimetou Mint Abdel Maleck.<\/p>\n<p>Son Excellence le Pr\u00e9sident de la R\u00e9publique \u00e9tait accompagn\u00e9 d&#8217;une d\u00e9l\u00e9gation de haut niveau comprenant :<\/p>\n<p>&#8211; Monsieur Nani Ould Chrougha, ministre charg\u00e9 du Cabinet du Pr\u00e9sident de la R\u00e9publique ;<\/p>\n<p>&#8211; Monsieur Mohamed Ahmed Dadeh, Charg\u00e9 d&#8217;Affaires \u00e0 l&#8217;Ambassade de notre pays \u00e0 Conakry ;<\/p>\n<p>&#8211; Monsieur Ahmed Ould Neini, Conseiller \u00e0 la Pr\u00e9sidence de la R\u00e9publique ;<\/p>\n<p>&#8211; Monsieur Ahmed Ould Bahini, Charg\u00e9 de Mission \u00e0 la Pr\u00e9sidence de la R\u00e9publique ;<\/p>\n<p>&#8211; Monsieur El Hacen Ould Ahmed, Directeur G\u00e9n\u00e9ral du Protocole d&#8217;\u00c9tat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Son Excellence le Pr\u00e9sident de la R\u00e9publique, Monsieur Mohamed Ould Cheikh El Ghazouani, a regagn\u00e9 ce samedi soir Nouakchott, en provenance de Conakry, apr\u00e8s avoir particip\u00e9 \u00e0 la c\u00e9r\u00e9monie d&#8217;investiture de Son Excellence Monsieur Mamady Doumbouya, Pr\u00e9sident de la R\u00e9publique de Guin\u00e9e. Son Excellence le Pr\u00e9sident de la R\u00e9publique a \u00e9t\u00e9 accueilli \u00e0 l&#8217;a\u00e9roport international [&hellip;]<\/p>\n","protected":false},"author":53,"featured_media":287453,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63957,63921],"tags":[],"class_list":["post-287446","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fil-dactualite","category-slider-afficher"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/287446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=287446"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/287446\/revisions"}],"predecessor-version":[{"id":287448,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/287446\/revisions\/287448"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/287453"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=287446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=287446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=287446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}