{"id":286017,"date":"2025-12-21T20:01:54","date_gmt":"2025-12-21T20:01:54","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=286017"},"modified":"2025-12-21T20:01:54","modified_gmt":"2025-12-21T20:01:54","slug":"le-ministre-de-la-culture-visite-le-pavillon-des-jeux-traditionnels","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/286017","title":{"rendered":"Le ministre de la Culture visite le pavillon des jeux traditionnels"},"content":{"rendered":"<p>Le ministre de la Culture, des Arts, de la Communication et des Relations avec Parlement, porte-parole du gouvernement, M. Houssein Ould Medou, accompagn\u00e9 du wali de l&#8217;Adrar, M. Abdallahi Ould Mohamed Mahmoud, a visit\u00e9 ce dimanche apr\u00e8s-midi le pavillon des jeux traditionnels, organis\u00e9 dans le cadre du festival des cit\u00e9s du patrimoine.<\/p>\n<p>Au niveau du pavillon, quatre \u00e9quipes de chacune des villes historiques (Chinguittyi, Ouadane, Tichitt et Walata) participent \u00e0 cette comp\u00e9tition dans les domaines du sigue, de krour et de Thamett.<\/p>\n<p>D\u2019adressant aux \u00e9quipes en comp\u00e9tition, le ministre a appel\u00e9 les participants \u00e0 ces jeux \u00e0 faire preuve de transparence et de comp\u00e9titivit\u00e9 positive, ainsi qu&#8217;\u00e0 l&#8217;esprit de responsabilit\u00e9, de discipline et d&#8217;engagement \u00e9thique.<\/p>\n<p>Ces comp\u00e9titions se sont d\u00e9roul\u00e9es en pr\u00e9sence du secr\u00e9taire g\u00e9n\u00e9ral du minist\u00e8re de la Culture, du hakem de la moughataa de Ouadane et de son d\u00e9put\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le ministre de la Culture, des Arts, de la Communication et des Relations avec Parlement, porte-parole du gouvernement, M. Houssein Ould Medou, accompagn\u00e9 du wali de l&#8217;Adrar, M. Abdallahi Ould Mohamed Mahmoud, a visit\u00e9 ce dimanche apr\u00e8s-midi le pavillon des jeux traditionnels, organis\u00e9 dans le cadre du festival des cit\u00e9s du patrimoine. Au niveau du [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":286018,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63920,63957,8672],"tags":[],"class_list":["post-286017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-fil-dactualite","category-8672"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/286017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=286017"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/286017\/revisions"}],"predecessor-version":[{"id":286019,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/286017\/revisions\/286019"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/286018"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=286017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=286017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=286017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}