{"id":284267,"date":"2025-11-29T15:28:39","date_gmt":"2025-11-29T15:28:39","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=284267"},"modified":"2025-11-29T15:28:39","modified_gmt":"2025-11-29T15:28:39","slug":"rosso-organisation-dactivites-sportives-pour-commemorer-la-fete-de-lindependance-nationale","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/284267","title":{"rendered":"Rosso: Organisation d&#8217;activit\u00e9s sportives pour comm\u00e9morer la F\u00eate de l&#8217;Ind\u00e9pendance nationale"},"content":{"rendered":"<div class=\"row\"><\/div>\n<div class=\"row\">\n<div class=\"cell auto-size\">\n<div class=\"set-border bd-gray padding10 margin10 no-margin-right no-margin-left \" dir=\"ltr\">\n<p>Dans le cadre des activit\u00e9s comm\u00e9morant le 65e anniversaire de l\u2019Ind\u00e9pendance nationale, le wali adjoint de Trarza, M. Sidi Mohamed Sidina Nemine, accompagn\u00e9 du commandant du Centre de formation technique de l&#8217;Arm\u00e9e nationale \u00e0 Rosso, le colonel Ahmed Salem Bah Nou\u00e8h, et du hakem de la moughataa de Rosso, M. Mkhaitratt Ould Mohamed Vall, a supervis\u00e9 vendredi soir, dans les environs du village de &#8220;T\u00e9k\u00e9che Koumba&#8221;, l&#8217;organisation des comp\u00e9titions de tir traditionnel \u00e0 la cible.<\/p>\n<p>Un groupe d&#8217;officiers, de sous-officiers et de soldats de diverses branches militaires et de s\u00e9curit\u00e9, ainsi que des civils venus participer \u00e0 ces comp\u00e9titions ont particip\u00e9 au championnat, dont les trois premiers gagnants ont re\u00e7u des prix consid\u00e9rables.<\/p>\n<p>Au stade municipal de Ramdane \u00e0 Rosso, le conseiller du wali de Trarza charg\u00e9 des affaires \u00e9conomiques et du d\u00e9veloppement local, M. Yahya Banou Mohamed Lemine, accompagn\u00e9 du maire de la commune de Rosso, M. Bamba Ould Deramane, et du d\u00e9put\u00e9 de la moughataa de Rosso, M. Hamatt Fall, a supervis\u00e9 la cl\u00f4ture du championnat de football d&#8217;automne, dont le match final s&#8217;inscrit dans le cadre des activit\u00e9s comm\u00e9morant l&#8217;anniversaire de la F\u00eate de l&#8217;Ind\u00e9pendance nationale.<\/p>\n<p>Le match a oppos\u00e9 les \u00e9quipes &#8220;N\u2019diorbel&#8221; et &#8220;N&#8217;Dongay&#8221; et s&#8217;est termin\u00e9 par la victoire de la premi\u00e8re par deux buts \u00e0 un, remportant ainsi la coupe du championnat au milieu des acclamations et de l&#8217;enthousiasme des supporters.<\/p>\n<p>Le pr\u00e9sident de la Ligue sportive r\u00e9gionale, M. Bad Jean, a salu\u00e9 ce championnat qui a connu une large participation d&#8217;\u00e9quipes et dont les comp\u00e9titions ont dur\u00e9 deux mois, appr\u00e9ciant l&#8217;attention que l&#8217;\u00c9tat accorde au soutien du sport de base et au d\u00e9veloppement du football.<\/p>\n<p>La c\u00e9r\u00e9monie de cl\u00f4ture a \u00e9t\u00e9 marqu\u00e9e par l&#8217;hommage aux meilleurs niveaux sportifs et au corps arbitral.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre des activit\u00e9s comm\u00e9morant le 65e anniversaire de l\u2019Ind\u00e9pendance nationale, le wali adjoint de Trarza, M. Sidi Mohamed Sidina Nemine, accompagn\u00e9 du commandant du Centre de formation technique de l&#8217;Arm\u00e9e nationale \u00e0 Rosso, le colonel Ahmed Salem Bah Nou\u00e8h, et du hakem de la moughataa de Rosso, M. Mkhaitratt Ould Mohamed Vall, a [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":284268,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63918,63957],"tags":[],"class_list":["post-284267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autres","category-fil-dactualite"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/284267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=284267"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/284267\/revisions"}],"predecessor-version":[{"id":284269,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/284267\/revisions\/284269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/284268"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=284267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=284267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=284267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}