{"id":274623,"date":"2025-07-03T20:20:18","date_gmt":"2025-07-03T20:20:18","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=274623"},"modified":"2025-07-03T20:20:18","modified_gmt":"2025-07-03T20:20:18","slug":"lancement-dun-atelier-national-pour-verifier-les-resultats-de-lexamen-du-cadre-environnemental-et-social-de-la-banque-africaine-de-developpement","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/274623","title":{"rendered":"Lancement d&#8217;un atelier national pour v\u00e9rifier les r\u00e9sultats de l&#8217;examen du Cadre environnemental et social de la Banque africaine de d\u00e9veloppement"},"content":{"rendered":"<p>Les travaux d&#8217;un atelier national visant \u00e0 v\u00e9rifier les r\u00e9sultats de l&#8217;examen du Cadre environnemental et social de la Banque africaine de d\u00e9veloppement et sa conformit\u00e9 avec la l\u00e9gislation nationale ont d\u00e9but\u00e9 ce jeudi \u00e0 Nouakchott. L&#8217;atelier est organis\u00e9 par le Minist\u00e8re de l&#8217;Environnement et du D\u00e9veloppement Durable en collaboration avec la Banque africaine de d\u00e9veloppement.<\/p>\n<p>Cet atelier, d&#8217;une dur\u00e9e d&#8217;une journ\u00e9e, vise \u00e0 harmoniser les cadres environnementaux et sociaux nationaux et internationaux, \u00e0 renforcer la transparence dans la gestion des risques environnementaux et sociaux en Mauritanie, et \u00e0 am\u00e9liorer la pr\u00e9paration des institutions nationales pour la mise en \u0153uvre de projets conformes aux exigences du d\u00e9veloppement durable.<\/p>\n<p>Dans son discours d&#8217;ouverture de l&#8217;atelier, M. Ahmed Ould Zein, charg\u00e9 de mission au cabinet de la Ministre de l&#8217;Environnement et du D\u00e9veloppement Durable, a expliqu\u00e9 que l&#8217;atelier s&#8217;inscrit dans un contexte national important, o\u00f9 Son Excellence le Pr\u00e9sident de la R\u00e9publique, M. Mohamed Ould Cheikh El Ghazouani, a fait de la protection de l&#8217;environnement, de la durabilit\u00e9 des ressources naturelles et du renforcement de la justice climatique l&#8217;une des priorit\u00e9s de son programme \u00e9lectoral. Cela est mis en \u0153uvre \u00e0 travers les politiques publiques, notamment la Strat\u00e9gie nationale de croissance acc\u00e9l\u00e9r\u00e9e et de prosp\u00e9rit\u00e9 partag\u00e9e, dont la mise en \u0153uvre est supervis\u00e9e par le gouvernement sous la direction de Son Excellence le Premier Ministre, M. El Moctar Ould Djay.<\/p>\n<p>Il a ajout\u00e9 que le secteur de l&#8217;environnement et du d\u00e9veloppement travaille \u00e0 la mise en \u0153uvre d&#8217;un plan d&#8217;action ambitieux et int\u00e9gr\u00e9 bas\u00e9 sur la contribution nationale d\u00e9termin\u00e9e dans le cadre de l&#8217;Accord de Paris, la Strat\u00e9gie nationale pour l&#8217;environnement et le d\u00e9veloppement durable, et le Plan national d&#8217;adaptation, en plus des programmes nationaux de lutte contre la d\u00e9sertification, la perte de biodiversit\u00e9 et la pollution.<\/p>\n<p>Ould Zein a salu\u00e9 les efforts des \u00e9quipes du minist\u00e8re et des repr\u00e9sentants des secteurs concern\u00e9s, en collaboration avec des experts nationaux et internationaux, et avec le soutien de la Banque africaine de d\u00e9veloppement, pour l&#8217;\u00e9laboration de ce document de r\u00e9f\u00e9rence. Il a exprim\u00e9 l&#8217;espoir que l&#8217;atelier d\u00e9bouche sur des recommandations pratiques qui renforceront les capacit\u00e9s nationales du pays et soutiendront l&#8217;engagement de la Mauritanie envers un mod\u00e8le de d\u00e9veloppement \u00e9quilibr\u00e9, juste et durable.<\/p>\n<p>De son c\u00f4t\u00e9, M. Hercule Yamuremye, charg\u00e9 principal de programme pays du Groupe de la Banque africaine de d\u00e9veloppement en Mauritanie, a affirm\u00e9 que cette \u00e9valuation s&#8217;inscrit dans le cadre d&#8217;un engagement commun entre les gouvernements des \u00c9tats membres r\u00e9gionaux de la Banque et les partenaires au d\u00e9veloppement, dans le but de renforcer les cadres environnementaux et sociaux et d&#8217;\u00e9viter les lacunes habituelles dans ce domaine.<\/p>\n<p>Il a soulign\u00e9 que ces \u00e9tudes ont \u00e9t\u00e9 lanc\u00e9es avec le soutien de la Banque africaine de d\u00e9veloppement et de la Banque mondiale, et qu&#8217;elles couvrent jusqu&#8217;\u00e0 pr\u00e9sent 45 pays africains, soit l&#8217;\u00e9quivalent de 80% des \u00c9tats membres, et qu&#8217;elles seront achev\u00e9es dans les mois \u00e0 venir dans les neuf pays restants.<\/p>\n<p>Il a expliqu\u00e9 que ce processus permettra d&#8217;identifier les disparit\u00e9s existantes entre les l\u00e9gislations nationales et les syst\u00e8mes du Cadre environnemental et social de la Banque, afin d&#8217;\u00e9viter les retards dans la pr\u00e9paration et la mise en \u0153uvre des projets et de r\u00e9duire les impacts n\u00e9gatifs sur l&#8217;environnement et les communaut\u00e9s.<\/p>\n<p>Il a pr\u00e9cis\u00e9 que l&#8217;\u00e9valuation se concentre sur quatre axes principaux :<\/p>\n<p>&#8211; \u00c9tude du cadre l\u00e9gislatif, juridique et des politiques environnementales et sociales.<\/p>\n<p>&#8211; Analyse des \u00e9carts entre les exigences de la Banque africaine de d\u00e9veloppement et les l\u00e9gislations nationales.<\/p>\n<p>&#8211; \u00c9valuation des syst\u00e8mes et des capacit\u00e9s de gouvernance dans les pays concern\u00e9s.<\/p>\n<p>&#8211; \u00c9laboration de plans d&#8217;action pour validation lors d&#8217;ateliers nationaux.<\/p>\n<p>Il a conclu en soulignant que cet atelier national de validation s&#8217;inscrit dans une approche int\u00e9gr\u00e9e et participative, visant \u00e0 impliquer tous les acteurs afin d&#8217;adopter les r\u00e9sultats de l&#8217;examen du Cadre environnemental et social et de partager les recommandations qui d\u00e9couleront de l&#8217;atelier.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les travaux d&#8217;un atelier national visant \u00e0 v\u00e9rifier les r\u00e9sultats de l&#8217;examen du Cadre environnemental et social de la Banque africaine de d\u00e9veloppement et sa conformit\u00e9 avec la l\u00e9gislation nationale ont d\u00e9but\u00e9 ce jeudi \u00e0 Nouakchott. L&#8217;atelier est organis\u00e9 par le Minist\u00e8re de l&#8217;Environnement et du D\u00e9veloppement Durable en collaboration avec la Banque africaine de [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":274624,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63918,63957,63959],"tags":[],"class_list":["post-274623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autres","category-fil-dactualite","category-mauritanie"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/274623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=274623"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/274623\/revisions"}],"predecessor-version":[{"id":274625,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/274623\/revisions\/274625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/274624"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=274623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=274623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=274623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}