{"id":270256,"date":"2025-05-04T12:55:02","date_gmt":"2025-05-04T12:55:02","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=270256"},"modified":"2025-05-04T13:30:00","modified_gmt":"2025-05-04T13:30:00","slug":"delegation-de-lelevage-en-assaba-un-travail-concret-pour-proteger-lelevage-et-promouvoir-le-developpement-local","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/270256","title":{"rendered":"D\u00e9l\u00e9gation de l\u2019\u00c9levage en Assaba : Un travail concret pour prot\u00e9ger l&#8217;\u00e9levage et promouvoir le d\u00e9veloppement local"},"content":{"rendered":"<p>La D\u00e9l\u00e9gation r\u00e9gionale du minist\u00e8re de l\u2019\u00e9levage au niveau de la wilaya de l&#8217;Assaba poursuit ses efforts inlassables pour prot\u00e9ger et d\u00e9velopper l&#8217;\u00e9levage, pilier de l&#8217;\u00e9conomie locale et principale source de revenus pour pr\u00e8s de 60 % de la population.<\/p>\n<p>Dans une interview exclusive accord\u00e9e \u00e0 l&#8217;Agence Mauritanienne d\u2019Information (AMI), le D\u00e9l\u00e9gu\u00e9 r\u00e9gional, M. Yedaly Mohameden, a indiqu\u00e9 que la d\u00e9l\u00e9gation vaque \u00e0 la mise en \u0153uvre des programmes du d\u00e9partement dans la wilaya, par l&#8217;interm\u00e9diaire de ses cinq inspections couvrant les diff\u00e9rentes moughataas.<\/p>\n<p>Il a soulign\u00e9 que ces programmes comprennent l&#8217;encadrement v\u00e9t\u00e9rinaire, l&#8217;am\u00e9lioration de la sant\u00e9 animale, la surveillance \u00e9pid\u00e9miologique et la mise en place d&#8217;infrastructures de base.<\/p>\n<p>Une campagne de vaccination \u00e0 grande \u00e9chelle a \u00e9t\u00e9 lanc\u00e9e fin 2024 et prolong\u00e9e jusqu&#8217;au 10 mai.<\/p>\n<p>Cette campagne a obtenu des r\u00e9sultats records, d\u00e9passant les objectifs de 10 %, et pourrait atteindre un pourcentage plus \u00e9lev\u00e9 apr\u00e8s la prolongation.<\/p>\n<p>Les vaccinations ont cibl\u00e9 les maladies les plus courantes, telles que la peste des petits ruminants (PPR), la pneumonie et la pleur\u00e9sie contagieuses.<\/p>\n<p>En mati\u00e8re de contr\u00f4le v\u00e9t\u00e9rinaire int\u00e9gr\u00e9, la d\u00e9l\u00e9gation assure une surveillance sanitaire rigoureuse des march\u00e9s de viande et des points de vente gr\u00e2ce \u00e0 des \u00e9quipes techniques \u00e9quip\u00e9es de m\u00e9dicaments et de fournitures v\u00e9t\u00e9rinaires, et a mis en place des installations modernes telles que des abattoirs, des enclos de vaccination et des sites d&#8217;am\u00e9lioration g\u00e9n\u00e9tique.<\/p>\n<p>Les \u00e9quipes v\u00e9t\u00e9rinaires interviennent \u00e9galement rapidement en cas de sympt\u00f4mes de maladie chez le b\u00e9tail. Des \u00e9chantillons de laboratoire sont ainsi pr\u00e9lev\u00e9s et les cas suspects sont imm\u00e9diatement trait\u00e9s.<\/p>\n<p>Le d\u00e9l\u00e9gu\u00e9 a indiqu\u00e9 que l&#8217;\u00e9tat sanitaire du b\u00e9tail dans la wilaya est bon et qu&#8217;aucun cas n\u00e9cessitant une d\u00e9claration n&#8217;a \u00e9t\u00e9 enregistr\u00e9 r\u00e9cemment.<\/p>\n<p>Partenariats et coordination avec les acteurs locaux<\/p>\n<p>M. Yedaly Mohameden a confirm\u00e9 que la d\u00e9l\u00e9gation travaille en coordination avec la F\u00e9d\u00e9ration nationale de l\u2019\u00e9levage et le Groupement des associations pastorales, dans le cadre d&#8217;un partenariat visant \u00e0 informer et \u00e0 sensibiliser sur les questions v\u00e9t\u00e9rinaires.<\/p>\n<p>Dans le cadre d&#8217;une enqu\u00eate aupr\u00e8s des acteurs locaux, le maire de Nouamline et pr\u00e9sident de l&#8217;Association des maires de l&#8217;Assaba, M. Mohamed Yahya Taleb Zeidane, a soulign\u00e9 que la d\u00e9l\u00e9gation r\u00e9gionale est l&#8217;une des administrations les plus efficaces et les plus r\u00e9actives aux pr\u00e9occupations de la population.<\/p>\n<p>Il a appel\u00e9 \u00e0 l&#8217;organisation des \u00e9leveurs et \u00e0 la d\u00e9livrance de cartes professionnelles afin de faciliter l&#8217;octroi de l&#8217;aide gouvernementale \u00e0 ceux qui la m\u00e9ritent.<\/p>\n<p>Il a \u00e9galement appel\u00e9 \u00e0 la cr\u00e9ation d&#8217;une usine de produits laitiers et de cuir dans la wilaya pour une meilleure exploitation des ressources, soulignant l&#8217;importance d&#8217;un contr\u00f4le local des op\u00e9rations de recensement et des initiatives de d\u00e9veloppement pour garantir une mise en \u0153uvre pr\u00e9cise et efficace.<\/p>\n<p>De son c\u00f4t\u00e9, le pr\u00e9sident du Groupement des associations pastorales, M. Ethmane Ould Haiba, a salu\u00e9 les efforts de la d\u00e9l\u00e9gation et le succ\u00e8s des campagnes de vaccination, insistant sur l&#8217;importance de soutenir les \u00e9leveurs pendant la saison estivale, marqu\u00e9e par une p\u00e9nurie de p\u00e2turages.<\/p>\n<p>Il a \u00e9galement contest\u00e9 le classement de la wilaya dans le recensement national du b\u00e9tail, estimant que l&#8217;organisme charg\u00e9 de la mise en \u0153uvre manquait d&#8217;expertise, appelant \u00e0 l&#8217;implication des associations pastorales et des f\u00e9d\u00e9rations professionnelles dans ces op\u00e9rations.<\/p>\n<p>Pour sa part, l&#8217;\u00e9leveur Ahmed Ould Sidi Ould Ali a salu\u00e9 la contribution de la d\u00e9l\u00e9gation en mati\u00e8re d&#8217;encadrement et de suivi sanitaire des animaux, mais a mis en garde contre le risque d&#8217;incendies d\u00e9truisant les p\u00e2turages.<\/p>\n<p>De son c\u00f4t\u00e9, l&#8217;\u00e9leveur Hassan Ould Elma a plaid\u00e9 pour des prix subventionn\u00e9s des aliments pour animaux et de l&#8217;eau, compte tenu de leurs co\u00fbts \u00e9lev\u00e9s et de leur impact direct sur les \u00e9leveurs.<\/p>\n<p>En Assaba, la d\u00e9l\u00e9gation r\u00e9gionale de l\u2019\u00c9levage ne m\u00e9nage aucun effort \u00e0 travers des programmes ambitieux et des actions concr\u00e8tes sur le terrain en vue d\u2019un d\u00e9veloppement int\u00e9gr\u00e9 et durable des ressources pastorales.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-270257\" src=\"https:\/\/ami.mr\/fr\/wp-content\/uploads\/2025\/05\/Sans-titre-2-300x225.jpg\" alt=\"\" width=\"716\" height=\"537\" srcset=\"https:\/\/ami.mr\/fr\/wp-content\/uploads\/2025\/05\/Sans-titre-2-300x225.jpg 300w, https:\/\/ami.mr\/fr\/wp-content\/uploads\/2025\/05\/Sans-titre-2-768x576.jpg 768w, https:\/\/ami.mr\/fr\/wp-content\/uploads\/2025\/05\/Sans-titre-2-86x64.jpg 86w, https:\/\/ami.mr\/fr\/wp-content\/uploads\/2025\/05\/Sans-titre-2.jpg 840w\" sizes=\"(max-width: 716px) 100vw, 716px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La D\u00e9l\u00e9gation r\u00e9gionale du minist\u00e8re de l\u2019\u00e9levage au niveau de la wilaya de l&#8217;Assaba poursuit ses efforts inlassables pour prot\u00e9ger et d\u00e9velopper l&#8217;\u00e9levage, pilier de l&#8217;\u00e9conomie locale et principale source de revenus pour pr\u00e8s de 60 % de la population. Dans une interview exclusive accord\u00e9e \u00e0 l&#8217;Agence Mauritanienne d\u2019Information (AMI), le D\u00e9l\u00e9gu\u00e9 r\u00e9gional, M. Yedaly [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":270261,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63918,63957,8672],"tags":[],"class_list":["post-270256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autres","category-fil-dactualite","category-8672"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/270256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=270256"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/270256\/revisions"}],"predecessor-version":[{"id":270259,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/270256\/revisions\/270259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/270261"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=270256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=270256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=270256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}