{"id":270087,"date":"2025-05-01T20:11:23","date_gmt":"2025-05-01T20:11:23","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=270087"},"modified":"2025-05-01T20:41:51","modified_gmt":"2025-05-01T20:41:51","slug":"le-ministre-de-la-peche-et-son-homologue-turc-visitent-le-marche-aux-poissons-de-nouakchott","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/270087","title":{"rendered":"Le ministre de la P\u00eache et son homologue turc visitent le march\u00e9 aux poissons de Nouakchott"},"content":{"rendered":"<p>Le Ministre de la P\u00eache, des Infrastructures Maritimes et Portuaires, M. Fadil Ould Sidati Ould Ahmed Louli, accompagn\u00e9 de M. Abubeiar GIZLIGIDER, Ministre d\u00e9l\u00e9gu\u00e9 charg\u00e9 de la P\u00eache au Minist\u00e8re turc de l\u2019Agriculture et des For\u00eats, qui est actuellement en visite dans notre pays \u00e0 la t\u00eate d\u2019une d\u00e9l\u00e9gation de son secteur, a rendu visite, jeudi soir, au march\u00e9 aux poissons et \u00e0 la soci\u00e9t\u00e9 SDPP pour l\u2019emballage et l\u2019exportation du poisson.<\/p>\n<p>Le Ministre de la P\u00eache et des Infrastructures maritimes et portuaires accompagn\u00e9 de son invit\u00e9, a \u00e9cout\u00e9 les explications donn\u00e9es par les responsables de ces installations sur l\u2019avancement des travaux de ces deux institutions et des services qu\u2019elles offrent dans les installations de p\u00eache, notamment<\/p>\n<p>la fourniture et la valorisation du poisson frais, en plus des m\u00e9canismes d\u2019emballage et de stockage.<\/p>\n<p>Le Ministre \u00e9tait accompagn\u00e9 du Secr\u00e9taire g\u00e9n\u00e9ral du Minist\u00e8re,M. Sidi Ali Ould Sidi Boubacar, de plusieurs responsables centraux du secteur, des autorit\u00e9s administratives et \u00e9lues, et des autorit\u00e9s de s\u00e9curit\u00e9 de la wilaya de Nouakchott ouest.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Ministre de la P\u00eache, des Infrastructures Maritimes et Portuaires, M. Fadil Ould Sidati Ould Ahmed Louli, accompagn\u00e9 de M. Abubeiar GIZLIGIDER, Ministre d\u00e9l\u00e9gu\u00e9 charg\u00e9 de la P\u00eache au Minist\u00e8re turc de l\u2019Agriculture et des For\u00eats, qui est actuellement en visite dans notre pays \u00e0 la t\u00eate d\u2019une d\u00e9l\u00e9gation de son secteur, a rendu visite, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":270094,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63920,63957,63959,63927],"tags":[],"class_list":["post-270087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-fil-dactualite","category-mauritanie","category-slider-mauritanie"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/270087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=270087"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/270087\/revisions"}],"predecessor-version":[{"id":270090,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/270087\/revisions\/270090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/270094"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=270087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=270087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=270087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}