{"id":263670,"date":"2025-01-24T21:13:55","date_gmt":"2025-01-24T21:13:55","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=263670"},"modified":"2025-01-24T21:13:55","modified_gmt":"2025-01-24T21:13:55","slug":"atelier-de-concertation-sur-la-gestion-integree-des-ressources-en-eau-dans-la-wilaya-du-tagant","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/263670","title":{"rendered":"Atelier de concertation sur la gestion int\u00e9gr\u00e9e des ressources en eau dans la wilaya du Tagant"},"content":{"rendered":"<p>Un atelier de concertation sur la gestion int\u00e9gr\u00e9e des ressources en eau au niveau de la wilaya du Tagant, avec la participation des autorit\u00e9s administratives, des chefs de services et des \u00e9lus, en plus d&#8217;une mission du secteur de l&#8217;hydraulique et de l&#8217;assainissement, a d\u00e9marr\u00e9 vendredi matin au Tagant.<\/p>\n<p>S&#8217;exprimant \u00e0 cette occasion, le wali du Tagant, M. Mohamed Ould Ahmed Mouloud, a soulign\u00e9 que la gestion int\u00e9gr\u00e9e des ressources en eau au Tagant est une priorit\u00e9 absolue pour le gouvernement et une partie essentielle des Objectifs de d\u00e9veloppement durable (ODD).<\/p>\n<p>Il a soulign\u00e9 que la wilaya, malgr\u00e9 sa diversit\u00e9 naturelle, est confront\u00e9 \u00e0 des d\u00e9fis majeurs en termes de ressources en eau en raison de la p\u00e9nurie d&#8217;eau, du changement climatique et de l&#8217;irrigation indiscrimin\u00e9e, qui augmente la pression sur les ressources en eau.<\/p>\n<p>Cet atelier est une opportunit\u00e9 de discussion et d&#8217;\u00e9change d&#8217;exp\u00e9riences pour trouver les meilleurs moyens d&#8217;am\u00e9liorer la gestion int\u00e9gr\u00e9e des ressources en eau afin d&#8217;assurer les besoins de la population, a-t-il dit.<\/p>\n<p>Le vice-pr\u00e9sident de la r\u00e9gion du Tagant, M. Yahiana Ould Ahmed Cheikh, et l&#8217;adjointe au maire de la commune de Tidjikja, Aicha Mint Tourad, ont salu\u00e9 l&#8217;organisation de cet atelier, qui est une occasion de discuter de la situation des ressources en eau dans la wilaya et de formuler des recommandations appropri\u00e9es pour am\u00e9liorer l&#8217;acc\u00e8s des citoyens aux services de l&#8217;eau.<\/p>\n<p>Le directeur g\u00e9n\u00e9ral du Centre national des ressources en eau au minist\u00e8re de l&#8217;Hydraulique et de l&#8217;Assainissement, Mohamed Lemine Ould Khatri, a d\u00e9clar\u00e9 dans une allocution pr\u00e9alable que cet atelier permettra de faire la lumi\u00e8re sur une question qui touche notre pays en g\u00e9n\u00e9ral et le Tagant en particulier, \u00e0 savoir la raret\u00e9 de l&#8217;eau.<\/p>\n<p>Il a ajout\u00e9 que la wilaya souffre d&#8217;une p\u00e9nurie d&#8217;eaux de surface et d&#8217;eaux souterraines en raison de la raret\u00e9 des pr\u00e9cipitations due au changement climatique, ce qui n\u00e9cessite l&#8217;adoption d&#8217;une approche globale et durable, soulignant la n\u00e9cessit\u00e9 de d\u00e9velopper une vision globale qui prenne en compte tous les besoins, de l&#8217;eau potable aux besoins du secteur agricole.<\/p>\n<p>Le chef de cabinet du wali du Tagant, M. Mokhtar Ould Ahmed Ould Babe, et le hakem de Tidjikja, M. Mohamed Lemine Ould Zeine, ont particip\u00e9 \u00e0 l&#8217;atelier.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un atelier de concertation sur la gestion int\u00e9gr\u00e9e des ressources en eau au niveau de la wilaya du Tagant, avec la participation des autorit\u00e9s administratives, des chefs de services et des \u00e9lus, en plus d&#8217;une mission du secteur de l&#8217;hydraulique et de l&#8217;assainissement, a d\u00e9marr\u00e9 vendredi matin au Tagant. S&#8217;exprimant \u00e0 cette occasion, le wali [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":263672,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63918,63919,63957,63923],"tags":[],"class_list":["post-263670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autres","category-choix-du-redacteur","category-fil-dactualite","category-slider-wilayas"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/263670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=263670"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/263670\/revisions"}],"predecessor-version":[{"id":263673,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/263670\/revisions\/263673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/263672"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=263670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=263670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=263670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}