{"id":263133,"date":"2025-01-16T23:15:46","date_gmt":"2025-01-16T23:15:46","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=263133"},"modified":"2025-01-16T23:15:46","modified_gmt":"2025-01-16T23:15:46","slug":"lassemblee-nationale-adopte-le-projet-de-loi-regissant-les-etablissements-de-credit","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/263133","title":{"rendered":"L&#8217;Assembl\u00e9e nationale adopte le projet de loi r\u00e9gissant les \u00e9tablissements de cr\u00e9dit"},"content":{"rendered":"<p>L&#8217;Assembl\u00e9e nationale a approuv\u00e9, jeudi soir, lors d&#8217;une s\u00e9ance pr\u00e9sid\u00e9e par Mme Aghleyouh Aman Lehdhaane, quatri\u00e8me vice-pr\u00e9sidente de l&#8217;Assembl\u00e9e, le projet de loi n\u00b0 24-039, qui compl\u00e8te, abroge ou remplace certaines dispositions de la loi n\u00b0 2018-03\/R.C. bis, en date du 16 ao\u00fbt 2018, r\u00e9glementant les \u00e9tablissements de cr\u00e9dit.<\/p>\n<p>Le Ministre de l&#8217;Economie et des Finances, M. Sid&#8217;Ahmed Bouh, a expliqu\u00e9 que la loi actuelle r\u00e9gissant les \u00e9tablissements de cr\u00e9dit ne comporte pas de m\u00e9canismes clairs et progressifs pour traiter les banques en difficult\u00e9, ajoutant que les amendements propos\u00e9s dans ce projet de loi visent \u00e0 combler ces lacunes en d\u00e9finissant les proc\u00e9dures de traitement des banques en difficult\u00e9, dans un environnement devenu plus complexe que jamais.<\/p>\n<p>Le ministre a soulign\u00e9 que les dispositions propos\u00e9es sont en ad\u00e9quation avec les meilleures pratiques internationales actuelles, insistant sur l&#8217;importance d&#8217;un syst\u00e8me financier stable qui rassurera les acteurs \u00e9conomiques et soutiendra les activit\u00e9s \u00e9conomiques.<\/p>\n<p>Il a soulign\u00e9 que le projet de loi vise \u00e0 prot\u00e9ger les d\u00e9posants et \u00e0 promouvoir la stabilit\u00e9 financi\u00e8re en traitant les banques en difficult\u00e9 selon trois m\u00e9thodes, \u00e0 savoir : la rectification, le r\u00e8glement et la liquidation.<\/p>\n<p>Le ministre a rassur\u00e9 les d\u00e9put\u00e9s que le gouvernement est d\u00e9termin\u00e9 \u00e0 faire tout ce qui est en son pouvoir pour assurer la cr\u00e9dibilit\u00e9 et la transparence du syst\u00e8me financier, notant que des mesures ont \u00e9t\u00e9 prises pour prot\u00e9ger les banques et le syst\u00e8me financier contre les cyber-attaques.<\/p>\n<p>Il a soulign\u00e9 que la Banque Centrale de Mauritanie est en train de revoir le syst\u00e8me des amendes appliqu\u00e9es aux banques afin de mieux l&#8217;adapter au contexte.<\/p>\n<p><img decoding=\"async\" class=\"size-medium wp-image-263135 alignleft\" src=\"https:\/\/ami.mr\/fr\/wp-content\/uploads\/2025\/01\/Sans-titre-128-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/ami.mr\/fr\/wp-content\/uploads\/2025\/01\/Sans-titre-128-300x200.jpg 300w, https:\/\/ami.mr\/fr\/wp-content\/uploads\/2025\/01\/Sans-titre-128-1024x682.jpg 1024w, https:\/\/ami.mr\/fr\/wp-content\/uploads\/2025\/01\/Sans-titre-128-768x512.jpg 768w, https:\/\/ami.mr\/fr\/wp-content\/uploads\/2025\/01\/Sans-titre-128-1536x1023.jpg 1536w, https:\/\/ami.mr\/fr\/wp-content\/uploads\/2025\/01\/Sans-titre-128.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Pour leur part, les parlementaires ont exprim\u00e9 leur int\u00e9r\u00eat pour le projet de loi qui garantit la solidit\u00e9 du syst\u00e8me financier national et prot\u00e8ge les int\u00e9r\u00eats des diff\u00e9rents acteurs.<\/p>\n<p>Ils ont \u00e9galement abord\u00e9 la n\u00e9cessit\u00e9 de contr\u00f4ler les conditions d&#8217;agr\u00e9ment des \u00e9tablissements de cr\u00e9dit, d&#8217;accorder une plus grande attention aux normes professionnelles et \u00e9thiques, sans n\u00e9gliger les normes financi\u00e8res, de renforcer la gouvernance et le suivi des pr\u00eats, ainsi que les bases sur lesquelles les IMF sont class\u00e9es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Assembl\u00e9e nationale a approuv\u00e9, jeudi soir, lors d&#8217;une s\u00e9ance pr\u00e9sid\u00e9e par Mme Aghleyouh Aman Lehdhaane, quatri\u00e8me vice-pr\u00e9sidente de l&#8217;Assembl\u00e9e, le projet de loi n\u00b0 24-039, qui compl\u00e8te, abroge ou remplace certaines dispositions de la loi n\u00b0 2018-03\/R.C. bis, en date du 16 ao\u00fbt 2018, r\u00e9glementant les \u00e9tablissements de cr\u00e9dit. Le Ministre de l&#8217;Economie et des [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":263134,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63920,63957,63959,63927],"tags":[],"class_list":["post-263133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-fil-dactualite","category-mauritanie","category-slider-mauritanie"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/263133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=263133"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/263133\/revisions"}],"predecessor-version":[{"id":263136,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/263133\/revisions\/263136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/263134"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=263133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=263133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=263133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}