{"id":259115,"date":"2024-11-19T19:24:00","date_gmt":"2024-11-19T19:24:00","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=259115"},"modified":"2024-11-20T14:21:19","modified_gmt":"2024-11-20T14:21:19","slug":"le-premier-ministre-rencontre-les-presidents-des-partis-de-la-majorite","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/259115","title":{"rendered":"Le Premier ministre rencontre les pr\u00e9sidents des partis de la majorit\u00e9"},"content":{"rendered":"<div class=\"row\"><\/div>\n<div class=\"row\">\n<div class=\"cell auto-size\">\n<div class=\"set-border bd-gray padding10 margin10 no-margin-right no-margin-left \" dir=\"ltr\">\n<p>Dans le cadre de la coordination avec les partis de la majorit\u00e9, et conform\u00e9ment aux directives de Son Excellence Monsieur le Pr\u00e9sident de la R\u00e9publique Mohamed Ould Cheikh El-Ghazouani, le Premier ministre, M. Mokhtar Ould Diay, a rencontr\u00e9, mardi, au Premier minist\u00e8re, \u00e0 Nouakchott, les pr\u00e9sidents des partis de la majorit\u00e9 soutenant Son Excellence Monsieur le Pr\u00e9sident de la R\u00e9publique.<\/p>\n<p>La r\u00e9union a \u00e9t\u00e9 consacr\u00e9e \u00e0 un \u00e9change de vues sur les moyens de renforcer les m\u00e9canismes de coordination et de concertation entre le gouvernement et ces partis sur les grandes questions nationales et la n\u00e9cessit\u00e9 d&#8217;une action commune pour r\u00e9pondre aux aspirations des citoyens notamment en ce qui concerne le renforcement de la coh\u00e9sion nationale, la consolidation de la bonne gouvernance, l&#8217;am\u00e9lioration des conditions de vie des populations et \u00e0 l&#8217;assainissement du climat politique dans le pays.<\/p>\n<p>Le Premier ministre a assur\u00e9 les participants \u00e0 la r\u00e9union que la volont\u00e9 du gouvernement est de poursuivre ce type de rencontres afin d&#8217;\u00e9changer des informations et d&#8217;\u00e9tablir une plus grande coordination et concertation au sein de de la Majorit\u00e9 Pr\u00e9sidentielle.<\/p>\n<p>La r\u00e9union s&#8217;est d\u00e9roul\u00e9e en pr\u00e9sence du ministre charg\u00e9 du secr\u00e9tariat g\u00e9n\u00e9ral du Gouvernement, M. Mokhtar Lam Al Housseinou, du Directeur de Cabinet du Premier Ministre, M. Cheikh Ould Zidane, et de Mme Hindou Bint Ainina, Conseill\u00e8re du Premier Ministre charg\u00e9e des Affaires Politiques.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre de la coordination avec les partis de la majorit\u00e9, et conform\u00e9ment aux directives de Son Excellence Monsieur le Pr\u00e9sident de la R\u00e9publique Mohamed Ould Cheikh El-Ghazouani, le Premier ministre, M. Mokhtar Ould Diay, a rencontr\u00e9, mardi, au Premier minist\u00e8re, \u00e0 Nouakchott, les pr\u00e9sidents des partis de la majorit\u00e9 soutenant Son Excellence Monsieur [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":259116,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63919,63957,63959,63921,63927],"tags":[],"class_list":["post-259115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-choix-du-redacteur","category-fil-dactualite","category-mauritanie","category-slider-afficher","category-slider-mauritanie"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/259115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=259115"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/259115\/revisions"}],"predecessor-version":[{"id":259117,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/259115\/revisions\/259117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/259116"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=259115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=259115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=259115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}