{"id":254230,"date":"2024-09-15T12:57:10","date_gmt":"2024-09-15T12:57:10","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=254230"},"modified":"2024-09-15T12:57:10","modified_gmt":"2024-09-15T12:57:10","slug":"maghtalahjar-coup-denvoi-de-la-quatrieme-edition-des-prix-de-soutien-a-leducation-publique","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/254230","title":{"rendered":"Maghtalahjar : Coup d&#8217;envoi de la quatri\u00e8me \u00e9dition des prix de soutien \u00e0 l&#8217;\u00e9ducation publique"},"content":{"rendered":"<p>Le secr\u00e9taire g\u00e9n\u00e9ral du minist\u00e8re de l&#8217;\u00e9ducation nationale et de la r\u00e9forme de l&#8217;enseignement, M. Yahya Ould Taleb, ainsi que le wali adjoint du Brakna, M. Mohamed Abdelvettah Ould Ahmed, ont supervis\u00e9, samedi soir, au centre administratif de Djonaba, le lancement de la quatri\u00e8me \u00e9dition des prix de soutien \u00e0 l&#8217;enseignement public dans la moughataa de Maghtalahjar.<\/p>\n<p>Cette \u00e9dition s&#8217;inscrit dans la continuit\u00e9 de la mise en \u0153uvre du protocole d&#8217;accord sign\u00e9 entre le minist\u00e8re de l\u2019Education Nationale et de la R\u00e9forme de l&#8217;Enseignement et le d\u00e9put\u00e9 de Maghtalahjar, M. Ahmed Abou El Maali, visant \u00e0 encourager l&#8217;excellence dans l&#8217;enseignement public dans la moughataa.<\/p>\n<p>Le montant total de ce soutien, apport\u00e9 \u00e0 l&#8217;initiative du d\u00e9put\u00e9, s&#8217;\u00e9l\u00e8ve \u00e0 10 millions MRO, afin d&#8217;encourager ceux qui ont excell\u00e9 dans les concours nationaux dans les \u00e9tablissements d&#8217;enseignement public, ainsi que le personnel enseignant des \u00e9tablissements qui ont enregistr\u00e9s de tr\u00e8s bons r\u00e9sultats.<\/p>\n<p>Dans le discours qu&#8217;il a prononc\u00e9 \u00e0 cette occasion, le secr\u00e9taire g\u00e9n\u00e9ral du minist\u00e8re de l&#8217;\u00e9ducation nationale et de la r\u00e9forme de l\u2019enseignement a remerci\u00e9 le d\u00e9put\u00e9 pour cette initiative visant \u00e0 rehausser le niveau de l\u2019enseignement public.<\/p>\n<p>Il a ajout\u00e9 que l&#8217;accompagnement et le soutien des efforts de r\u00e9forme dans le secteur permettraient d&#8217;acc\u00e9l\u00e9rer le rythme de la transformation positive du syst\u00e8me \u00e9ducatif afin d&#8217;atteindre les objectifs souhait\u00e9s \u00e0 cet \u00e9gard, soulignant l&#8217;importance des initiatives locales dans la diffusion de l&#8217;esprit de don, d&#8217;assiduit\u00e9 et de pers\u00e9v\u00e9rance.<\/p>\n<p>Pour sa part, le d\u00e9put\u00e9 Ahmed Abou El Maali a soulign\u00e9 que cette initiative est ad\u00e9quation avec le programme \u00e9lectoral de Son Excellence le Pr\u00e9sident de la R\u00e9publique Mohamed Ould Cheikh Ghazouani qui a fait de la r\u00e9forme de l&#8217;\u00e9ducation et de l&#8217;instauration des valeurs de l&#8217;\u00e9cole r\u00e9publicaine la priorit\u00e9 des priorit\u00e9s.<\/p>\n<p>De son c\u00f4t\u00e9, M. Mustapha Habib, maire de la commune de Djonaba, a salu\u00e9 cette initiative qu&#8217;il consid\u00e8re comme l&#8217;un des moyens les plus importants pour stimuler l&#8217;acquisition du savoir et d\u00e9velopper le rendement des \u00e9tudiants et des \u00e9l\u00e8ves de l&#8217;enseignement public, cr\u00e9ant ainsi un certain \u00e9quilibre et une \u00e9mulation positive dans le domaine de l&#8217;\u00e9ducation.<\/p>\n<p>Pour sa part, M. Mohamed El Moustapha Ould Mohamed Mahmoud, pr\u00e9sident de la r\u00e9gion du Brakna, a soulign\u00e9 que ces prix cr\u00e9ent une dynamique \u00e9mulation positive dans l&#8217;enseignement public, ce qui se refl\u00e8te positivement sur les taux de r\u00e9ussite, exprimant ses remerciements au d\u00e9put\u00e9 pour cette importante initiative.<\/p>\n<p>La c\u00e9r\u00e9monie s&#8217;est d\u00e9roul\u00e9e en pr\u00e9sence du hakem de la moughataa de Maghtalahjar, du chef de l\u2019arrondissement administratif de Djonaba, de la d\u00e9put\u00e9e de Maghtalahjar, Mme Fatima Salma Sidi Hamoud, et des autorit\u00e9s s\u00e9curitaires de la wilaya.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le secr\u00e9taire g\u00e9n\u00e9ral du minist\u00e8re de l&#8217;\u00e9ducation nationale et de la r\u00e9forme de l&#8217;enseignement, M. Yahya Ould Taleb, ainsi que le wali adjoint du Brakna, M. Mohamed Abdelvettah Ould Ahmed, ont supervis\u00e9, samedi soir, au centre administratif de Djonaba, le lancement de la quatri\u00e8me \u00e9dition des prix de soutien \u00e0 l&#8217;enseignement public dans la moughataa [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":254231,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63918,63957,8672],"tags":[],"class_list":["post-254230","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autres","category-fil-dactualite","category-8672"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/254230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=254230"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/254230\/revisions"}],"predecessor-version":[{"id":254232,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/254230\/revisions\/254232"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/254231"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=254230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=254230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=254230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}