{"id":248262,"date":"2024-06-14T03:28:35","date_gmt":"2024-06-14T03:28:35","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=248262"},"modified":"2024-07-04T13:15:04","modified_gmt":"2024-07-04T13:15:04","slug":"le-candidat-mohamed-lemine-el-mourtaji-el-wafi-ouvre-sa-campagne-electorale-depuis-nema","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/248262","title":{"rendered":"Le candidat Mohamed Lemine El Mourtaji El Wafi ouvre sa campagne \u00e9lectorale depuis N\u00e9ma"},"content":{"rendered":"<p>Le candidat \u00e0 l&#8217;\u00e9lection pr\u00e9sidentielle de 2024, Mohamed Lemine El Mourtaji El Wafi, a ouvert sa campagne \u00e9lectorale pour les \u00e9lections du 29 juin dans sa ville natale, N\u00e9ma, capitale de la wilaya du Hodh Charghi.<\/p>\n<p>Dans un discours prononc\u00e9 \u00e0 cette occasion, le candidat, qui se pr\u00e9sente \u00e0 la course pr\u00e9sidentielle pour la deuxi\u00e8me fois apr\u00e8s les \u00e9lections de 2019, a jur\u00e9 par le Saint Coran d\u2019assurer avec honn\u00eatet\u00e9 et sinc\u00e9rit\u00e9 la gestion des affaires du pays, s&#8217;il est \u00e9lu, appelant les autres candidats \u00e0 suivre son exemple si leurs intentions sont sinc\u00e8res pour mener les r\u00e9formes dans le pays.<\/p>\n<p>M. Ould El Wafi a appel\u00e9 les jeunes instruits et travailleurs, capables de s&#8217;\u00e9lever contre l&#8217;injustice sans craindre de nuire \u00e0 leurs int\u00e9r\u00eats ou d&#8217;\u00eatre licenci\u00e9s, \u00e0 se lancer dans la politique et \u00e0 \u0153uvrer pour ramener la pratique politique sur la bonne voie afin de sauver la soci\u00e9t\u00e9 et d&#8217;apporter secours aux orphelins, aux n\u00e9cessiteux et aux groupes vuln\u00e9rables en g\u00e9n\u00e9ral, au lieu de r\u00e9pondre aux besoins personnels de certains.<\/p>\n<p>Il a d\u00e9plor\u00e9 que la pratique de la politique soit devenue une honte en raison de la flatterie et des mensonges qui l&#8217;entachent.<\/p>\n<p>Le jeune candidat a soulign\u00e9 que c&#8217;\u00e9tait l&#8217;\u00e9lite qui se partageait les positions et contr\u00f4lait les ressources du pays sans tenir compte de la grande majorit\u00e9 du peuple, appelant le peuple \u00e0 changer ce st\u00e9r\u00e9otype et \u00e0 le surmonter en votant pour quelqu&#8217;un qui le repr\u00e9sente et qui vit et conna\u00eet sa r\u00e9alit\u00e9.<\/p>\n<p>Il a exhort\u00e9 ses partisans et sympathisants \u00e0 suivre l&#8217;exemple du peuple s\u00e9n\u00e9galais en votant pour un Pr\u00e9sident jeune qui ressent leurs besoins, affirmant que c&#8217;est \u00e0 eux de prendre l&#8217;initiative, d&#8217;\u00eatre optimistes et de ne pas faire preuve de passivit\u00e9 et de d\u00e9sespoir.<\/p>\n<p>Au d\u00e9but de la c\u00e9r\u00e9monie d&#8217;ouverture, M. Ould El Wafi a souhait\u00e9 la bienvenue \u00e0 l&#8217;assistance dans ce climat difficile, en particulier \u00e0 la gent f\u00e9minine, et a pr\u00e9sent\u00e9 ses excuses \u00e0 son \u00e9quipe de campagne \u00e0 Nouakchott pour ne pas avoir respect\u00e9 le programme d&#8217;ouverture \u00e0 Nouakchott, expliquant que les &#8220;conditions difficiles dans la ville de N\u00e9ma&#8221; l&#8217;ont incit\u00e9 \u00e0 ouvrir sa campagne \u00e0 partir de cette ville.<\/p>\n<p>La c\u00e9r\u00e9monie d&#8217;ouverture s&#8217;est d\u00e9roul\u00e9e en pr\u00e9sence du staff de campagne du candidat,\u00a0 et d&#8217;un groupe de ses partisans.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le candidat \u00e0 l&#8217;\u00e9lection pr\u00e9sidentielle de 2024, Mohamed Lemine El Mourtaji El Wafi, a ouvert sa campagne \u00e9lectorale pour les \u00e9lections du 29 juin dans sa ville natale, N\u00e9ma, capitale de la wilaya du Hodh Charghi. Dans un discours prononc\u00e9 \u00e0 cette occasion, le candidat, qui se pr\u00e9sente \u00e0 la course pr\u00e9sidentielle pour la deuxi\u00e8me [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":249503,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63957,63959],"tags":[63961],"class_list":["post-248262","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fil-dactualite","category-mauritanie","tag-presidentielles-2024"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/248262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=248262"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/248262\/revisions"}],"predecessor-version":[{"id":248265,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/248262\/revisions\/248265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/249503"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=248262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=248262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=248262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}