{"id":248245,"date":"2024-06-13T20:24:55","date_gmt":"2024-06-13T20:24:55","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=248245"},"modified":"2024-06-13T20:24:55","modified_gmt":"2024-06-13T20:24:55","slug":"le-ministre-des-affaires-etrangeres-recoit-lambassadrice-dallemagne-11","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/248245","title":{"rendered":"Le ministre des Affaires \u00e9trang\u00e8res re\u00e7oit l&#8217;ambassadrice d\u2019Allemagne"},"content":{"rendered":"<div class=\"row\"><\/div>\n<div class=\"row\">\n<div class=\"cell auto-size\">\n<div class=\"set-border bd-gray padding10 margin10 no-margin-right no-margin-left \" dir=\"ltr\">\n<p>Le ministre des Affaires \u00e9trang\u00e8res, de la Coop\u00e9ration et des Mauritaniens de l&#8217;Ext\u00e9rieur, M. Mohamed Salem Ould Merzoug, a re\u00e7u, jeudi \u00e0 Nouakchott, l&#8217;ambassadrice de la R\u00e9publique f\u00e9d\u00e9rale d\u2019Allemagne accr\u00e9dit\u00e9e aupr\u00e8s de notre pays, S.E. Mme Isabelle Hennin.<\/p>\n<p>L&#8217;entretien a port\u00e9 sur les relations de coop\u00e9ration entre les deux pays, les moyens de les renforcer et de les d\u00e9velopper, ainsi que sur les questions d&#8217;int\u00e9r\u00eat commun.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le ministre des Affaires \u00e9trang\u00e8res, de la Coop\u00e9ration et des Mauritaniens de l&#8217;Ext\u00e9rieur, M. Mohamed Salem Ould Merzoug, a re\u00e7u, jeudi \u00e0 Nouakchott, l&#8217;ambassadrice de la R\u00e9publique f\u00e9d\u00e9rale d\u2019Allemagne accr\u00e9dit\u00e9e aupr\u00e8s de notre pays, S.E. Mme Isabelle Hennin. L&#8217;entretien a port\u00e9 sur les relations de coop\u00e9ration entre les deux pays, les moyens de les renforcer [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":248246,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63918,63957],"tags":[],"class_list":["post-248245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autres","category-fil-dactualite"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/248245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=248245"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/248245\/revisions"}],"predecessor-version":[{"id":248247,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/248245\/revisions\/248247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/248246"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=248245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=248245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=248245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}