{"id":242894,"date":"2024-03-27T17:51:32","date_gmt":"2024-03-27T17:51:32","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=242894"},"modified":"2024-03-28T12:45:03","modified_gmt":"2024-03-28T12:45:03","slug":"au-conseil-des-ministres-approbation-de-conventions-detablissement-dans-le-domaine-du-tourisme","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/242894","title":{"rendered":"Au Conseil des Ministres, approbation de conventions d\u2019\u00e9tablissement dans le domaine du tourisme"},"content":{"rendered":"<p>Le Conseil des ministres s\u2019est r\u00e9uni le mercredi 27 mars 2024, sous la pr\u00e9sidence de Son Excellence Monsieur le Pr\u00e9sident de la R\u00e9publique, Mohamed Ould Cheikh El Ghazouani.<\/p>\n<p>Le Conseil a examin\u00e9 et adopt\u00e9 les projets de d\u00e9crets suivants :<\/p>\n<p>\u2010 Projet de d\u00e9cret portant approbation d\u2019une convention d\u2019\u00e9tablissement entre le Gouvernement de la R\u00e9publique Islamique de Mauritanie et la Soci\u00e9t\u00e9 Fasq Sarl.<\/p>\n<p>Ce projet de d\u00e9cret a pour objectif de permettre \u00e0 la Soci\u00e9t\u00e9 Fasq Sarl de cr\u00e9er un complexe touristique au bord de la plage de Nouakchott, qui va contribuer \u00e0 am\u00e9liorer l\u2019offre de service dans le cercle de l\u2019h\u00f4tellerie et du tourisme de la ville. Il comprendra 40 suites haut standing, 120 chambres, 40 tentes modernes, 4 grands restaurants, 4 piscines, pour adultes et enfants, 2 parcs de jeux, 1 terrain de football et 1 terrain de handball.<\/p>\n<p>Par ailleurs, ce projet, qui est en parfaite harmonie avec la strat\u00e9gie nationale du tourisme 2018-2030 et dont le co\u00fbt global s\u2019\u00e9l\u00e8ve \u00e0 760 Millions MRU, va permettre la cr\u00e9ation de 50 emplois directs et 57 indirects, en plus d\u2019assurer le renforcement des capacit\u00e9s du personnel mauritanien qui sera recrut\u00e9.<\/p>\n<p>\u2010 Projet de d\u00e9cret portant approbation d\u2019une convention d\u2019\u00e9tablissement entre le Gouvernement de la R\u00e9publique Islamique de Mauritanie et la Soci\u00e9t\u00e9 Al Dhafra pour l\u2019Investissement SARL.<\/p>\n<p>Ce projet de d\u00e9cret a pour objectif d\u2019autoriser \u00e0 la Soci\u00e9t\u00e9 Al Dhafra pour l\u2019Investissement SARL de cr\u00e9er un complexe h\u00f4telier au bord de la plage de Nouakchott, qui viendrait renforcer l\u2019offre de service et la capacit\u00e9 d\u2019accueil des h\u00f4tels de la ville. Il comprendra un parc d\u2019attraction, un parc aquatique, deux restaurants et des h\u00e9bergements de type bungalow.<\/p>\n<p>Ce projet, qui est en parfaite harmonie avec la strat\u00e9gie nationale du tourisme 2018-2030 et dont le co\u00fbt global s\u2019\u00e9l\u00e8ve \u00e0 111.700.000 MRU, va permettre la cr\u00e9ation de 65 emplois directs et 100 indirects, en plus d\u2019assurer le renforcement des capacit\u00e9s du personnel mauritanien qui sera recrut\u00e9.<\/p>\n<p>\u2010 Projet de d\u00e9cret portant nomination du Pr\u00e9sident et des membres du Conseil d\u2019Administration du Centre Hospitalier de Bassiknou.<\/p>\n<p>Le Ministre de la Justice a pr\u00e9sent\u00e9 une communication relative au Plan d\u2019Action National de lutte contre la Traite des Personnes 2024-2026.<\/p>\n<p>Cette communication a inform\u00e9 le Gouvernement sur l\u2019importance du Plan d\u2019Action National de lutte contre la Traite des Personnes 2024-2026, qui constitue un instrument de planification int\u00e9gr\u00e9 permettant \u00e0 la Mauritanie de lutter efficacement et durablement contre ce fl\u00e9au, r\u00e9primer les auteurs des infractions, identifier, prot\u00e9ger et assister les t\u00e9moins.<\/p>\n<p>Le Ministre des Affaires Etrang\u00e8res, de la Coop\u00e9ration et des Mauritaniens de l\u2019Ext\u00e9rieur a pr\u00e9sent\u00e9 une communication relative \u00e0 la situation internationale.<\/p>\n<p>Le Ministre de l\u2019Int\u00e9rieur et de la D\u00e9centralisation a pr\u00e9sent\u00e9 une communication relative \u00e0 la situation int\u00e9rieure.<\/p>\n<p>Le Ministre du P\u00e9trole, des Mines et de l\u2019Energie a pr\u00e9sent\u00e9 une communication relative \u00e0 l\u2019autorisation de signature d\u2019un contrat d\u2019Exploration-Production (CEP) avec le consortium \u00ab Taga Arabia &amp; GoGas \u00bb sur le bloc de Banda &amp; Tevet.<\/p>\n<p>Cette communication a inform\u00e9 le Gouvernement sur l\u2019importance de ce contrat qui vise, conform\u00e9ment \u00e0 la politique de promotion adopt\u00e9e, \u00e0 acc\u00e9l\u00e9rer le rythme des activit\u00e9s d\u2019exploration et d\u2019exploitation dans le bassin c\u00f4tier. De m\u00eame, il a \u00e9t\u00e9 rappel\u00e9 que le d\u00e9veloppement de Banda n\u00e9cessite la conclusion de ce contrat, conform\u00e9ment aux dispositions du code des hydrocarbures bruts, et les que n\u00e9gociations avec le consortium ont abouti \u00e0 la d\u00e9termination des termes techniques, \u00e9conomiques et fiscaux du Contrat-Production sur le bloc.<\/p>\n<p>Le Ministre de la Culture, de la Jeunesse des Sports et des Relations avec le Parlement a pr\u00e9sent\u00e9 une communication relative \u00e0 la Strat\u00e9gie Nationale de la Jeunesse 2024-2030.<\/p>\n<p>Cette communication a pr\u00e9sent\u00e9 au Gouvernement un diagnostic sur la situation du secteur de la jeunesse, mettant l\u2019accent sur les retards enregistr\u00e9s, notamment dans le domaine des infrastructures et sur les le\u00e7ons tir\u00e9es des strat\u00e9gies et politiques pr\u00e9c\u00e9dentes, avant de pr\u00e9senter la Strat\u00e9gie Nationale de la Jeunesse 2024-2030 et de proposer un dispositif institutionnel de mise en \u0153uvre, accompagn\u00e9 d\u2019un plan op\u00e9rationnel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Conseil des ministres s\u2019est r\u00e9uni le mercredi 27 mars 2024, sous la pr\u00e9sidence de Son Excellence Monsieur le Pr\u00e9sident de la R\u00e9publique, Mohamed Ould Cheikh El Ghazouani. Le Conseil a examin\u00e9 et adopt\u00e9 les projets de d\u00e9crets suivants : \u2010 Projet de d\u00e9cret portant approbation d\u2019une convention d\u2019\u00e9tablissement entre le Gouvernement de la R\u00e9publique [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":242957,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63919,63957,63959,63921,63927],"tags":[],"class_list":["post-242894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-choix-du-redacteur","category-fil-dactualite","category-mauritanie","category-slider-afficher","category-slider-mauritanie"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/242894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=242894"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/242894\/revisions"}],"predecessor-version":[{"id":242896,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/242894\/revisions\/242896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/242957"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=242894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=242894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=242894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}