{"id":235268,"date":"2023-12-05T11:29:01","date_gmt":"2023-12-05T11:29:01","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=235268"},"modified":"2023-12-05T11:29:01","modified_gmt":"2023-12-05T11:29:01","slug":"le-ministre-de-linterieur-se-reunit-avec-les-autorites-administratives-des-wilayas-du-pole-nord","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/235268","title":{"rendered":"Le ministre de l\u2019Int\u00e9rieur se r\u00e9unit avec les autorit\u00e9s administratives des wilayas du p\u00f4le nord"},"content":{"rendered":"<p>Le ministre de l\u2019Int\u00e9rieur et de la D\u00e9centralisation, M. Mohamed Ahmed Ould Mohamed Lemine, a tenu, hier lundi \u00e0 Atar, une r\u00e9union avec les autorit\u00e9s administratives des wilayas de l&#8217;Adrar, de Dakhlet- Nouadhibou, du Tagant, du Tirs Zemmour et de l&#8217;Inchiri.<\/p>\n<p>Dans son intervention, le ministre a insist\u00e9 sur la n\u00e9cessit\u00e9 de mettre l\u2019accent sur l\u2019investissement au service du pays et sur la motivation du fonctionnaire \u00e0 faire les sacrifices n\u00e9cessaires, ajoutant que l&#8217;action de son d\u00e9partement vise l\u2019am\u00e9lioration des conditions des autorit\u00e9s administratives, mat\u00e9riellement et moralement afin qu&#8217;elles puissent s&#8217;acquitter convenablement de leur mission.<\/p>\n<p>M. Mohamed Ahmed Ould Mohamed Lemine a demand\u00e9 aux autorit\u00e9s administratives de traduire dans les faits les orientations du Pr\u00e9sident de la R\u00e9publique, Son Excellence Monsieur Mohamed Ould Cheikh El Ghazouani permettant d\u2019assurer la r\u00e9alisation d\u2019un d\u00e9veloppement r\u00e9gional harmonieux et r\u00e9ussi.<\/p>\n<p>Le ministre a \u00e9galement invit\u00e9 les autorit\u00e9s administratives \u00e0 redoubler d\u2019efforts pour sensibiliser les citoyens \u00e0 une participation \u00e0 la r\u00e9ussite du projet de l&#8217;\u00e9cole r\u00e9publicaine et sur la n\u00e9cessit\u00e9 de se faire recenser sur le registre de l\u2019\u00e9tat civil avant de r\u00e9pondre aux intervenants.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le ministre de l\u2019Int\u00e9rieur et de la D\u00e9centralisation, M. Mohamed Ahmed Ould Mohamed Lemine, a tenu, hier lundi \u00e0 Atar, une r\u00e9union avec les autorit\u00e9s administratives des wilayas de l&#8217;Adrar, de Dakhlet- Nouadhibou, du Tagant, du Tirs Zemmour et de l&#8217;Inchiri. Dans son intervention, le ministre a insist\u00e9 sur la n\u00e9cessit\u00e9 de mettre l\u2019accent sur [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":235269,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63920,63957,8672],"tags":[],"class_list":["post-235268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-fil-dactualite","category-8672"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/235268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=235268"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/235268\/revisions"}],"predecessor-version":[{"id":235270,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/235268\/revisions\/235270"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/235269"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=235268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=235268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=235268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}