{"id":234182,"date":"2023-11-20T23:53:31","date_gmt":"2023-11-20T23:53:31","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=234182"},"modified":"2023-11-20T23:53:31","modified_gmt":"2023-11-20T23:53:31","slug":"la-commission-des-finances-de-lassemblee-examine-le-budget-du-ministere-de-la-transformation-numerique","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/234182","title":{"rendered":"La commission des Finances de l\u2019Assembl\u00e9e examine le budget du minist\u00e8re de la Transformation num\u00e9rique"},"content":{"rendered":"<p>a Commission des finances de l\u2019Assembl\u00e9e nationale a consacr\u00e9 sa s\u00e9ance tenue lundi sous la pr\u00e9sidence de M. Moustapha Sidi Hamoud, son pr\u00e9sident, \u00e0 l\u2019examen du budget du minist\u00e8re de la Transformation num\u00e9rique, de l\u2019Innovation et de la Modernisation de l\u2019administration dans le projet de loi de finances pour l\u2019ann\u00e9e 2024.<\/p>\n<p>Au cours de la r\u00e9union, la commission a suivi une pr\u00e9sentation du ministre de la Transformation num\u00e9rique, de l\u2019Innovation et de la Modernisation de l\u2019administration, M. Mohamed Abdallahi Ould Louli, dans laquelle il a pass\u00e9 en revue les chapitres de ce budget et les diff\u00e9rents domaines de ses d\u00e9penses.<\/p>\n<p>Le budget de ce minist\u00e8re dans le projet de loi de finances initial est de 550686540 Ouguiyas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>a Commission des finances de l\u2019Assembl\u00e9e nationale a consacr\u00e9 sa s\u00e9ance tenue lundi sous la pr\u00e9sidence de M. Moustapha Sidi Hamoud, son pr\u00e9sident, \u00e0 l\u2019examen du budget du minist\u00e8re de la Transformation num\u00e9rique, de l\u2019Innovation et de la Modernisation de l\u2019administration dans le projet de loi de finances pour l\u2019ann\u00e9e 2024. Au cours de la [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":234183,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63918,63919,63957],"tags":[],"class_list":["post-234182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autres","category-choix-du-redacteur","category-fil-dactualite"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/234182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=234182"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/234182\/revisions"}],"predecessor-version":[{"id":234184,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/234182\/revisions\/234184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/234183"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=234182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=234182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=234182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}