{"id":232536,"date":"2023-10-25T20:29:50","date_gmt":"2023-10-25T20:29:50","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=232536"},"modified":"2023-10-25T20:52:56","modified_gmt":"2023-10-25T20:52:56","slug":"le-president-de-la-republique-tient-une-reunion-avec-la-commissaire-europeen-a-lenergie","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/232536","title":{"rendered":"Le Pr\u00e9sident de la R\u00e9publique tient une r\u00e9union avec la commissaire europ\u00e9enne \u00e0 l&#8217;\u00e9nergie"},"content":{"rendered":"<p>Son Excellence le Pr\u00e9sident de la R\u00e9publique, M. Mohamed Ould Cheikh El Ghazouani, a tenu mercredi, une r\u00e9union au si\u00e8ge de l&#8217;Union europ\u00e9enne \u00e0 Bruxelles, avec la commissaire de l&#8217;Union europ\u00e9enne charg\u00e9e de l&#8217;\u00e9nergie, Mme Kadri Simson.<\/p>\n<p>Les \u00e9changes ont port\u00e9 sur les moyens propres \u00e0 promouvoir la coop\u00e9ration dans le domaine de l&#8217;\u00e9nergie entre notre pays et l&#8217;Union europ\u00e9enne.<\/p>\n<p>La r\u00e9union s&#8217;est d\u00e9roul\u00e9e en pr\u00e9sence du ministre charg\u00e9 du Cabinet de la Pr\u00e9sidence de la R\u00e9publique, M. Mokhtar Ould Diay, du ministre de l&#8217;\u00c9conomie et du D\u00e9veloppement durable, M. Abdessalam Ould Mohamed Saleh, de l&#8217;ambassadeur de notre pays \u00e0 Bruxelles, M. Mohamed Mahmoud Ould Brahim Khlil, et de SEM. Gwilym Jones, ambassadeur et chef de la d\u00e9l\u00e9gation de l&#8217;Union europ\u00e9enne accr\u00e9dit\u00e9e aupr\u00e8s de Notre pays.<\/p>\n<p>Cette r\u00e9union intervient apr\u00e8s que Son Excellence le Pr\u00e9sident de la R\u00e9publique ait sign\u00e9 hier avec le Pr\u00e9sident de la Commission europ\u00e9enne un document visant \u00e0 d\u00e9velopper les infrastructures appropri\u00e9es pour la production et le d\u00e9veloppement de l&#8217;hydrog\u00e8ne vert en Mauritanie, document qui vise \u00e0 permettre la production, le transport et la commercialisation de l\u2019hydrog\u00e8ne vert. Ces r\u00e9unions ont lieu en marge du Global Gateway Forum, organis\u00e9 par l&#8217;Union europ\u00e9enne mercredi et jeudi dans la capitale belge.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Son Excellence le Pr\u00e9sident de la R\u00e9publique, M. Mohamed Ould Cheikh El Ghazouani, a tenu mercredi, une r\u00e9union au si\u00e8ge de l&#8217;Union europ\u00e9enne \u00e0 Bruxelles, avec la commissaire de l&#8217;Union europ\u00e9enne charg\u00e9e de l&#8217;\u00e9nergie, Mme Kadri Simson. Les \u00e9changes ont port\u00e9 sur les moyens propres \u00e0 promouvoir la coop\u00e9ration dans le domaine de l&#8217;\u00e9nergie entre [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":232537,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63919,63957,63921],"tags":[],"class_list":["post-232536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-choix-du-redacteur","category-fil-dactualite","category-slider-afficher"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/232536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=232536"}],"version-history":[{"count":3,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/232536\/revisions"}],"predecessor-version":[{"id":232540,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/232536\/revisions\/232540"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/232537"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=232536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=232536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=232536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}