{"id":230306,"date":"2023-09-22T19:07:41","date_gmt":"2023-09-22T19:07:41","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=230306"},"modified":"2023-09-22T19:07:41","modified_gmt":"2023-09-22T19:07:41","slug":"le-ministre-des-affaires-etrangeres-participe-a-une-reunion-du-secretaire-detat-americain-avec-ses-homologues-de-la-cedeao","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/230306","title":{"rendered":"Le ministre des Affaires \u00e9trang\u00e8res participe \u00e0 une r\u00e9union du secr\u00e9taire d&#8217;\u00c9tat am\u00e9ricain avec ses homologues de la CEDEAO"},"content":{"rendered":"<div class=\"row\"><\/div>\n<div class=\"row\">\n<div class=\"cell auto-size\">\n<div class=\"set-border bd-gray padding10 margin10 no-margin-right no-margin-left \" dir=\"ltr\">\n<p>Le ministre des Affaires \u00e9trang\u00e8res, de la Coop\u00e9ration et des Mauritaniens \u00e0 l&#8217;Ext\u00e9rieur, M. Mohamed Salem Ould Merzoug, a particip\u00e9, vendredi \u00e0 New York, en marge de la 78\u00e8me session de l&#8217;Assembl\u00e9e g\u00e9n\u00e9rale des Nations Unies, \u00e0 une r\u00e9union pr\u00e9sid\u00e9e par le secr\u00e9taire d&#8217;\u00c9tat am\u00e9ricain, Anthony Blinken, avec les ministres des Affaires \u00e9trang\u00e8res de la Communaut\u00e9 \u00e9conomique des \u00c9tats de l&#8217;Afrique de l&#8217;Ouest, sur la crise du Niger.<\/p>\n<p>Ont particip\u00e9 \u00e0 cette r\u00e9union, outre le ministre, l&#8217;ambassadrice de Mauritanie \u00e0 Washington, Mme Ciss\u00e9 Cheikh Beida, et l&#8217;ambassadeur affect\u00e9 au cabinet du ministre, M. Hasni Lefkih.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le ministre des Affaires \u00e9trang\u00e8res, de la Coop\u00e9ration et des Mauritaniens \u00e0 l&#8217;Ext\u00e9rieur, M. Mohamed Salem Ould Merzoug, a particip\u00e9, vendredi \u00e0 New York, en marge de la 78\u00e8me session de l&#8217;Assembl\u00e9e g\u00e9n\u00e9rale des Nations Unies, \u00e0 une r\u00e9union pr\u00e9sid\u00e9e par le secr\u00e9taire d&#8217;\u00c9tat am\u00e9ricain, Anthony Blinken, avec les ministres des Affaires \u00e9trang\u00e8res de la [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":230307,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63920,63957],"tags":[],"class_list":["post-230306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-fil-dactualite"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/230306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=230306"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/230306\/revisions"}],"predecessor-version":[{"id":230308,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/230306\/revisions\/230308"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/230307"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=230306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=230306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=230306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}