{"id":223964,"date":"2023-06-16T09:50:13","date_gmt":"2023-06-16T09:50:13","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=223964"},"modified":"2023-06-16T09:50:13","modified_gmt":"2023-06-16T09:50:13","slug":"le-president-de-la-republique-felicite-son-homologue-islandais","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/223964","title":{"rendered":"Le Pr\u00e9sident de la R\u00e9publique f\u00e9licite son homologue islandais"},"content":{"rendered":"<p>Le Pr\u00e9sident de la R\u00e9publique, Son Excellence M. Mohamed Ould Cheikh El Ghazouani a adress\u00e9 vendredi le message de f\u00e9licitations qui suit au Pr\u00e9sident de la R\u00e9publique d&#8217;Island, Son Excellence M. Gu\u00f0ni Th. J\u00f3hannesso, \u00e0 occasion de la c\u00e9l\u00e9bration de la f\u00eate nationale de son pays.<\/p>\n<p>Le message est ainsi libell\u00e9<\/p>\n<p>&#8220;Excellence<\/p>\n<p>La f\u00eate nationale de votre pays m&#8217;offre l&#8217;agr\u00e9able occasion d&#8217;exprimer \u00e0 votre excellence mes chaleureuses f\u00e9licitations et de souhaiter au peuple islandais ami plus de progr\u00e8s et de prosp\u00e9rit\u00e9.<\/p>\n<p>Je tiens \u00e0 vous renouveler notre d\u00e9termination \u00e0 poursuivre les efforts visant \u00e0 renforcer et \u00e0 d\u00e9velopper les relations de coop\u00e9ration unissant nos deux pays dans l&#8217;int\u00e9r\u00eat mutuel de nos deux peuples amis.<\/p>\n<p>Veuillez recevoir, Excellence, l&#8217;expression de ma tr\u00e8s haute consid\u00e9ration.<\/p>\n<p>Mohamed Ould Cheikh El Ghazouani&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Pr\u00e9sident de la R\u00e9publique, Son Excellence M. Mohamed Ould Cheikh El Ghazouani a adress\u00e9 vendredi le message de f\u00e9licitations qui suit au Pr\u00e9sident de la R\u00e9publique d&#8217;Island, Son Excellence M. Gu\u00f0ni Th. J\u00f3hannesso, \u00e0 occasion de la c\u00e9l\u00e9bration de la f\u00eate nationale de son pays. Le message est ainsi libell\u00e9 &#8220;Excellence La f\u00eate nationale [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":223965,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63957,63959,63921,63927],"tags":[],"class_list":["post-223964","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fil-dactualite","category-mauritanie","category-slider-afficher","category-slider-mauritanie"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/223964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=223964"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/223964\/revisions"}],"predecessor-version":[{"id":223966,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/223964\/revisions\/223966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/223965"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=223964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=223964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=223964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}