{"id":209016,"date":"2022-10-29T12:15:01","date_gmt":"2022-10-29T12:15:01","guid":{"rendered":"https:\/\/ami.mr\/fr\/?p=209016"},"modified":"2022-10-29T12:15:01","modified_gmt":"2022-10-29T12:15:01","slug":"le-ministre-de-lagriculture-effectue-une-visite-dinformation-au-guidimagha","status":"publish","type":"post","link":"https:\/\/ami.mr\/fr\/archives\/209016","title":{"rendered":"Le ministre de l&#8217;agriculture effectue une visite d&#8217;information au Guidimagha"},"content":{"rendered":"<p>Le ministre de l&#8217;Agriculture, M. Yahya Ould Ahmed El Waghef, accompagn\u00e9 du Wali de Guidimagha, M. Ahmed Ould Mohamed Mahmoud Ould Dieh, s&#8217;est rendu, vendredi soir, au si\u00e8ge de la d\u00e9l\u00e9gation r\u00e9gionale du minist\u00e8re de l&#8217;Agriculture au niveau du Guidimagha et dans certaines coop\u00e9ratives agricoles de la ville de S\u00e9libabi.<\/p>\n<p>La visite, qui s&#8217;inscrit dans le cadre du suivi de la campagne agricole pour la saison 2022\/2023, vise \u00e0 s\u2019informer sur la situation de l&#8217;agriculture et sur le r\u00f4le que jouent les coop\u00e9ratives f\u00e9minines dans le domaine du d\u00e9veloppement agricole local et sur les probl\u00e8mes auxquels elles sont confront\u00e9es.<\/p>\n<p>Le ministre a re\u00e7u des explications d\u00e9taill\u00e9es des responsables de ces fermes, pr\u00e9sentant des \u00e9chantillons de leur production et posant les probl\u00e8mes dont souffrent ces coop\u00e9ratives, notamment dans le domaine de l&#8217;irrigation et de la protection des champs (Grillages).<\/p>\n<p>Au niveau de la d\u00e9l\u00e9gation r\u00e9gional, le ministre a suivi un expos\u00e9 technique pr\u00e9sent\u00e9 par le d\u00e9l\u00e9gu\u00e9 r\u00e9gional du minist\u00e8re, M. Mohamed Ould El Arby, qui s\u2019est appesanti sur la sp\u00e9cificit\u00e9 agricole de la wilaya du Guidimagha qui a connu cette ann\u00e9e une importante pluviom\u00e9trie d\u00e9passant les 800 mm augurant d\u2019une saison agricole prometteuse.<\/p>\n<p>L\u2019expos\u00e9 met en garde cependant contre les ravageurs agricoles, notamment les granivores et les criquets ainsi que certains insectes nuisibles aux cultures traditionnelles.<\/p>\n<p>Dans le cadre du volet pluvial, le d\u00e9l\u00e9gu\u00e9 r\u00e9gional souligne que la wilaya dispose d&#8217;environ 80 000 hectares, dont un quart est cultiv\u00e9 pendant la saison des pluies, notant qu&#8217;il est pr\u00e9vu qu&#8217;entre 25 mille et 30 mille hectares seront cultiv\u00e9s selon la programmation de la d\u00e9l\u00e9gation pour cette ann\u00e9e.<\/p>\n<p>En ce qui concerne l&#8217;agriculture irrigu\u00e9e, le d\u00e9l\u00e9gu\u00e9 a soulign\u00e9 dans son expos\u00e9 que la wilaya comprend environ 6000 hectares irrigu\u00e9s, dont seulement 185 hectares sont exploit\u00e9s pendant la campagne agricole en cours, en raison des probl\u00e8mes pos\u00e9s au niveau du fleuve et du manque de pompes.<\/p>\n<p>A propos de la campagne maraich\u00e8re au Guidimagha, il a indiqu\u00e9 qu\u2019elle se termine en mars du fait d\u2019une grave p\u00e9nurie d&#8217;eau d&#8217;irrigation.<\/p>\n<p>Il a pass\u00e9 en revue les probl\u00e8mes les plus importants auxquels est confront\u00e9 le travail de la d\u00e9l\u00e9gation, notamment en ce qui concerne le manque de cadres humains, de moyens logistiques et de magasins pour stocker les semences, les outils agricoles l\u00e9gers et les pesticides, en plus du retard dans l&#8217;arriv\u00e9e des semences de c\u00e9r\u00e9ales et de l\u00e9gumes et l&#8217;absence d&#8217;inspections locales du minist\u00e8re.<\/p>\n<p>L&#8217;agriculture de la wilaya souffre \u00e9galement du ph\u00e9nom\u00e8ne d&#8217;\u00e9rosion et de la d\u00e9gradation des sols, de l&#8217;absence d\u2019ouvrages hydrauliques, malgr\u00e9 l\u2019importante pluviosit\u00e9 de la wilaya.<\/p>\n<p>La visite a concern\u00e9 \u00e9galement le groupement des coop\u00e9ratives f\u00e9minines du Guidimagha, qui a \u00e9t\u00e9 cr\u00e9\u00e9e en 2000 comprenant 252 coop\u00e9ratives auxquelles sont affili\u00e9es femmes.<\/p>\n<p>Ce groupement intervient dans quatre moughataas et 18 communes. Ces coop\u00e9ratives souffrent du manque d&#8217;eau d&#8217;irrigation et des d\u00e9g\u00e2ts caus\u00e9s par les animaux en divagation.<\/p>\n<p>Le minist\u00e8re a, en outre visit\u00e9, la ferme du quartier Salama dans la ville de S\u00e9libabi.<\/p>\n<p>Cette ferme souffre de l&#8217;absence de cl\u00f4ture pour la prot\u00e9ger des animaux errants et d&#8217;un manque aigu d&#8217;eau d&#8217;irrigation pour la culture maraich\u00e8re \u00e0 plus grande \u00e9chelle.<\/p>\n<p>La visite s\u2019est d\u00e9roul\u00e9e en pr\u00e9sence du d\u00e9put\u00e9 de la moughtaa de S\u00e9libabi, M. Sidney Sokhna, du conseiller technique du ministre de l&#8217;agriculture charg\u00e9 des campagnes agricoles, M. Mohamed Ould Nemine, du conseiller technique du ministre de l&#8217;Agriculture charg\u00e9 de la protection des v\u00e9g\u00e9taux, M. Barry Adama, du directeur G\u00e9n\u00e9ral de la SONADER M. Momma Ould Beibeta et du directeur G\u00e9n\u00e9ral de la SNAAT, M. Khattry Ould Atigh, ainsi que du hakem de la moughataa de S\u00e9libabi, de l\u2019adjoint du maire de sa commune et des autorit\u00e9s militaires et s\u00e9curitaires de la wilaya.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le ministre de l&#8217;Agriculture, M. Yahya Ould Ahmed El Waghef, accompagn\u00e9 du Wali de Guidimagha, M. Ahmed Ould Mohamed Mahmoud Ould Dieh, s&#8217;est rendu, vendredi soir, au si\u00e8ge de la d\u00e9l\u00e9gation r\u00e9gionale du minist\u00e8re de l&#8217;Agriculture au niveau du Guidimagha et dans certaines coop\u00e9ratives agricoles de la ville de S\u00e9libabi. La visite, qui s&#8217;inscrit dans [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":209017,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63918,63957,8672],"tags":[],"class_list":["post-209016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autres","category-fil-dactualite","category-8672"],"_links":{"self":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/209016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/comments?post=209016"}],"version-history":[{"count":1,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/209016\/revisions"}],"predecessor-version":[{"id":209018,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/posts\/209016\/revisions\/209018"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media\/209017"}],"wp:attachment":[{"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/media?parent=209016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/categories?post=209016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ami.mr\/fr\/wp-json\/wp\/v2\/tags?post=209016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}